{"id":22481,"date":"2022-02-02T21:48:20","date_gmt":"2022-02-02T20:48:20","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?post_type=tribe_events&#038;p=22481"},"modified":"2022-02-06T02:34:22","modified_gmt":"2022-02-06T01:34:22","slug":"lichess-q-liga-r189-50-2","status":"publish","type":"tribe_events","link":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/","title":{"rendered":"Lichess-Q-Liga (R190) 3+0"},"content":{"rendered":"<p><strong><span style=\"color: #0000ff;\">Lichess-Q-Liga (R190):<\/span><span style=\"color: #ff0000;\"> Sonntag<\/span><\/strong><strong><span style=\"color: #ff0000;\">, 06.02.2022, 20:01 &#8211; 21:41 Uhr<\/span> (3 min + 0 sec) &#8211;<span style=\"color: #008000;\"> <a style=\"color: #008000;\" href=\"https:\/\/lichess.org\/tournament\/bkdO1UUN\"><span style=\"text-decoration: underline;\">Hier geht&#8217;s zum Turnier<\/span><\/a><\/span><\/strong><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Lichess-Q-Liga (R190): Sonntag, 06.02.2022, 20:01 &#8211; 21:41 Uhr (3 min + 0 sec) &#8211; Hier geht&#8217;s zum Turnier<\/p>\n","protected":false},"author":5,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[26,171],"coauthors":[50],"class_list":["post-22481","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-allgemein","tribe_events_cat-blitzschach-online","cat_allgemein","cat_blitzschach-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Lichess-Q-Liga (R190): Sonntag, 06.02.2022, 20:01 &#8211; 21:41 Uhr (3 min + 0 sec) &#8211; Hier geht&#8217;s zum Turnier\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-06T01:34:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Christian Greiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/lichess-q-liga-r189-50-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/lichess-q-liga-r189-50-2\\\/\",\"name\":\"Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2022-02-02T20:48:20+00:00\",\"dateModified\":\"2022-02-06T01:34:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/lichess-q-liga-r189-50-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/lichess-q-liga-r189-50-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/lichess-q-liga-r189-50-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lichess-Q-Liga (R190) 3+0\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/","og_locale":"de_DE","og_type":"article","og_title":"Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.","og_description":"Lichess-Q-Liga (R190): Sonntag, 06.02.2022, 20:01 &#8211; 21:41 Uhr (3 min + 0 sec) &#8211; Hier geht&#8217;s zum Turnier","og_url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/","og_site_name":"SC Weisse Dame e.V.","article_modified_time":"2022-02-06T01:34:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Christian Greiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/","name":"Lichess-Q-Liga (R190) 3+0 - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2022-02-02T20:48:20+00:00","dateModified":"2022-02-06T01:34:22+00:00","breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/lichess-q-liga-r189-50-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"http:\/\/sc-weisse-dame.de\/v3\/events\/"},{"@type":"ListItem","position":3,"name":"Lichess-Q-Liga (R190) 3+0"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/22481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":2,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/22481\/revisions"}],"predecessor-version":[{"id":22503,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/22481\/revisions\/22503"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=22481"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=22481"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events_cat?post=22481"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=22481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}