{"id":18592,"date":"2021-01-20T23:54:40","date_gmt":"2021-01-20T22:54:40","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?post_type=tribe_events&#038;p=18592"},"modified":"2021-01-20T23:54:40","modified_gmt":"2021-01-20T22:54:40","slug":"deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2","status":"publish","type":"tribe_events","link":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/","title":{"rendered":"Deutsche Schach-Online-Liga (R2 vs SF Hamburg)"},"content":{"rendered":"<p><a href=\"https:\/\/dsol.schachbund.de\/mannschaft.php?s=2021&amp;l=2a&amp;m=2\">Zur Turnierseite des DSB<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Turnierseite des DSB<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[26,154],"coauthors":[49],"class_list":["post-18592","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-allgemein","tribe_events_cat-online-schach","cat_allgemein","cat_online-schach"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.\" \/>\n<meta property=\"og:description\" content=\"Zur Turnierseite des DSB\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e. V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thorsten Gro\u00df\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\\\/\",\"name\":\"Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2021-01-20T22:54:40+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deutsche Schach-Online-Liga (R2 vs SF Hamburg)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e. V.\",\"description\":\"Herzlich Willkommen!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.","og_description":"Zur Turnierseite des DSB","og_url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/","og_site_name":"SC Weisse Dame e. V.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thorsten Gro\u00df"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/","name":"Deutsche Schach-Online-Liga (R2 vs SF Hamburg) - SC Weisse Dame e. V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2021-01-20T22:54:40+00:00","breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-schach-online-liga-r1-vs-su-ebersberg-grafing-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"http:\/\/sc-weisse-dame.de\/v3\/events\/"},{"@type":"ListItem","position":3,"name":"Deutsche Schach-Online-Liga (R2 vs SF Hamburg)"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e. V.","description":"Herzlich Willkommen!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/18592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/18592\/revisions"}],"predecessor-version":[{"id":18593,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/18592\/revisions\/18593"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=18592"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=18592"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events_cat?post=18592"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=18592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}