{"id":1783,"date":"2016-09-11T22:22:34","date_gmt":"2016-09-11T20:22:34","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/event\/deutsche-laendermeisterschaft\/"},"modified":"2016-09-11T22:22:34","modified_gmt":"2016-09-11T20:22:34","slug":"deutsche-laendermeisterschaft","status":"publish","type":"tribe_events","link":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/","title":{"rendered":"Deutsche L\u00e4ndermeisterschaft"},"content":{"rendered":"<p>Deutsche L\u00e4ndermeisterschaft in HannoverMit Minh und Nam in der Auswahlmannschaft des BSV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche L\u00e4ndermeisterschaft in HannoverMit Minh und Nam in der Auswahlmannschaft des BSV<\/p>\n","protected":false},"author":10,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[25],"coauthors":[],"class_list":["post-1783","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-jugend","cat_jugend"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Deutsche L\u00e4ndermeisterschaft in HannoverMit Minh und Nam in der Auswahlmannschaft des BSV\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudia M\u00fcnstermann\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-laendermeisterschaft\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-laendermeisterschaft\\\/\",\"name\":\"Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2016-09-11T20:22:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-laendermeisterschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-laendermeisterschaft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/deutsche-laendermeisterschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deutsche L\u00e4ndermeisterschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.","og_description":"Deutsche L\u00e4ndermeisterschaft in HannoverMit Minh und Nam in der Auswahlmannschaft des BSV","og_url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/","og_site_name":"SC Weisse Dame e.V.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Claudia M\u00fcnstermann"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/","url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/","name":"Deutsche L\u00e4ndermeisterschaft - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2016-09-11T20:22:34+00:00","breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/deutsche-laendermeisterschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"http:\/\/sc-weisse-dame.de\/v3\/events\/"},{"@type":"ListItem","position":3,"name":"Deutsche L\u00e4ndermeisterschaft"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/1783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/1783\/revisions"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=1783"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=1783"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events_cat?post=1783"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=1783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}