{"id":11053,"date":"2019-01-24T21:58:24","date_gmt":"2019-01-24T20:58:24","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?post_type=tribe_events&#038;p=11053"},"modified":"2019-01-24T21:59:23","modified_gmt":"2019-01-24T20:59:23","slug":"bmm-4-runde-auswaerts-2-2-2-2-2","status":"publish","type":"tribe_events","link":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/","title":{"rendered":"BMM (9. Runde) ausw\u00e4rts"},"content":{"rendered":"<p>ZWEITE bei Friesen Lichtenberg<\/p>\n<p>DRITTE bei Tempelhof<\/p>\n<p>VIERTE und SECHSTE bei SG Wei\u00dfensee<\/p>\n<p>F\u00dcNFTE und SIEBTE bei Zitadelle Spandau<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZWEITE bei Friesen Lichtenberg DRITTE bei Tempelhof VIERTE und SECHSTE bei SG Wei\u00dfensee F\u00dcNFTE und SIEBTE bei Zitadelle Spandau &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[26,45],"coauthors":[49],"class_list":["post-11053","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-allgemein","tribe_events_cat-bmm","cat_allgemein","cat_bmm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"ZWEITE bei Friesen Lichtenberg DRITTE bei Tempelhof VIERTE und SECHSTE bei SG Wei\u00dfensee F\u00dcNFTE und SIEBTE bei Zitadelle Spandau &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-24T20:59:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thorsten Gro\u00df\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/bmm-4-runde-auswaerts-2-2-2-2-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/bmm-4-runde-auswaerts-2-2-2-2-2\\\/\",\"name\":\"BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2019-01-24T20:58:24+00:00\",\"dateModified\":\"2019-01-24T20:59:23+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/bmm-4-runde-auswaerts-2-2-2-2-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/bmm-4-runde-auswaerts-2-2-2-2-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/termine\\\/bmm-4-runde-auswaerts-2-2-2-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BMM (9. Runde) ausw\u00e4rts\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/","og_locale":"de_DE","og_type":"article","og_title":"BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.","og_description":"ZWEITE bei Friesen Lichtenberg DRITTE bei Tempelhof VIERTE und SECHSTE bei SG Wei\u00dfensee F\u00dcNFTE und SIEBTE bei Zitadelle Spandau &nbsp; &nbsp;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/","og_site_name":"SC Weisse Dame e.V.","article_modified_time":"2019-01-24T20:59:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thorsten Gro\u00df"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/","name":"BMM (9. Runde) ausw\u00e4rts - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2019-01-24T20:58:24+00:00","dateModified":"2019-01-24T20:59:23+00:00","breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/termine\/bmm-4-runde-auswaerts-2-2-2-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"http:\/\/sc-weisse-dame.de\/v3\/events\/"},{"@type":"ListItem","position":3,"name":"BMM (9. Runde) ausw\u00e4rts"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/11053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/11053\/revisions"}],"predecessor-version":[{"id":11054,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events\/11053\/revisions\/11054"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=11053"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=11053"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tribe_events_cat?post=11053"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=11053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}