{"id":5848,"date":"2017-09-03T12:00:25","date_gmt":"2017-09-03T10:00:25","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=5848"},"modified":"2017-09-10T17:31:05","modified_gmt":"2017-09-10T15:31:05","slug":"nvm-u14-live-partien","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/","title":{"rendered":"NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Und wieder eine Live-\u00dcbertragung\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"http:\/\/dvm.schnix.de\/live.html\">Turnierseite<\/a> \u00a0\u00a0\u00a0 \u00a0 <\/strong><a href=\"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-2017-in-magdeburg\/\"><strong>Hendriks WeDa<\/strong>&#8211;<strong>Rundenberichte<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">Zum Abschluss ein Sieg gegen den Setzlistenersten und k\u00fcnftigen JBL-Konkurrenten bringt den 4. Platz in der Endtabelle. Der SV Empor Berlin belegt den Silberrang und wahrscheinlich hat sich auch der SV Mattnetz als F\u00fcnftplatzierter f\u00fcr die DVM zwischen Weihnachten uns Neujahr qualifiziert&#8230; &#8211; was f\u00fcr eine Berliner Ausbeute!!! Damit endet der Live-Stream hier aus Magdeburg. Nach der Siegerehrung gibt es f\u00fcr die Mannschaft evtl. noch ein Quali-Eis bevor es zur\u00fcck nach Berlin geht!<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify\">Eine dringender Wunsch an die IT-Abteilung des Ausrichters w\u00e4re, die Live-\u00dcbertragung an <strong><em>allen<\/em> <\/strong>Brettern zu erm\u00f6glichen, denn in den vergangenen Tagen haperte es gelegentlich an den Brettern 3 und 4. <span style=\"color: #ff0000\"><del>Leider sieht es aktuell so aus, dass die Live-\u00dcbertragung gar nicht funktioniert. Es werden die Partien der 6. Runde angezeigt. \ud83d\ude41<\/del><br \/>\n <\/span><\/p>\n<p style=\"text-align: justify\"><strong>Seit ca. 10:00 Uhr sind wenigstens die ersten beiden Bretter zu sehen &#8230;<br \/>\n Das Spitzenspiel h\u00e4lt an Spannung, was es verspricht!<br \/>\n <\/strong><\/p>\n<p style=\"text-align: justify\"><strong><span style=\"color: #ff0000\">10:45 Hakob hat gewonnen!!<\/span><span style=\"color: #ff0000\"><br \/>\n <\/span><\/strong><span style=\"color: #000000\">Das <\/span><span style=\"color: #000000\">Nam steht gut und Minh recht ausgeglichen. Kevin steht eine schwere Verteidigung bevor.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>11:00 Nam hat einen Turm mehr! Kompensation ist nicht in Sicht f\u00fcr den Gegner.<br \/>\n <\/strong><span style=\"color: #000000\">Minh steht sehr ausgeglichen und Kevin weiterhin schwierig. Aber ein 2:2 w\u00fcrde ja schon reichen zur Qualifikation. \ud83d\ude42<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>11:11 Nam gewonnen!! Die Qualifikation zur DVM ist damit erreicht!!! <br \/>\n <\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>11:58 Kevin kann seine schwierige Stellung bei h\u00e4ngendem Pl\u00e4ttchen nicht mehr verteidigen und geht Matt. Anschlusstreffer f\u00fcr Reideburg.<\/strong> <\/span><br \/>\n Minh steht im Endspiel mit T\u00fcrmen und Springern sehr ausgeglichen.<\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>12:29 Der Norddeutsche Meister in der U14 steht fest. Der Hamburger SK gewinnt als einziges der drei Spitzenteams die letzte Runde und sichert sich damit erneut den Meistertitel. Herzlichen Gl\u00fcckwunsch!<\/strong><\/span><br \/>\n Der SV Empor Berlin kommt gegen G\u00f6ttingen nicht \u00fcber ein 2:2 hinaus und wird Vizemeister. Wir werden vermutlich punktgleich mit den Reidburgern 4., sofern Minh nicht noch gewinnt. <br \/>\n Der SV Mattnetz hat sein letztes Spiel knapp gewonnen und ist damit sogar noch im Rennen um den letzten Qualifikationsplatz. So ganz \u00fcberblicken kann ich es aber nicht bei der Mannschafts-SoBerg.<\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>12:48 Bei Minh gibts wenig Neues.<\/strong><\/span> Ein Endspiel mit jeweils Turm, Springer und 4 Bauern und fast symmetrischer Bauernstruktur. Beide Spieler haben noch \u00fcber 20 Minuten auf der Uhr und die Partie n\u00e4hert sich dem 60. Zug.<\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\"><strong>13:10 Minh holt das Remis. <\/strong><\/span>Zum Abschluss ein Sieg gegen den Setzlistenersten und k\u00fcnftigen JBL-Konkurrenten bringt den 4. Platz in der Endtabelle. Der SV Empor Berlin belegt den Silberrang und wahrscheinlich hat sich auch der SV Mattnetz als F\u00fcnftplatzierter f\u00fcr die DVM zwischen Weihnachten uns Neujahr qualifiziert&#8230; &#8211; was f\u00fcr eine Berliner Ausbeute!!!<\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R7: WeDa &#8211; Reideburg &#8211; Endstand um 13:00 Uhr 2,5:1,5<\/strong><\/p>\n<p style=\"text-align: justify\"><strong><em>&#8222;Finale furioso!&#8220;<\/em><\/strong> Um die Teilnahme an der &#8222;Deutschen&#8220; zu sichern, bedarf es eines starken Auftritts gegen den bereits qualifizierten Ranglistenersten Reideburg. Momentan steht WeDa auf dem 4. Rang und die Ausgangsposition ist besser als noch vor der 6. Runde. Es gilt nun, sich gegen die Besten zu behaupten; nur dann ist die Qualifikation auch wirklich verdient. Also: <strong><em>&#8222;Kopf hoch &#8211; und volle Konzentration!&#8220;<\/em><\/strong><\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R6: WeDa &#8211; Rochade G\u00f6ttingen &#8211; Endstand um 17:30 Uhr 3:1<\/strong><\/p>\n<p style=\"text-align: justify\">Noch k\u00f6nnen wir die Qualifikation zur &#8222;Deutschen&#8220; aus eigener Kraft schaffen, obwohl drei der f\u00fcnf Pl\u00e4tze bereits sicher vergeben zu sein scheinen an Reideburg, Empor Berlin und den HSK (alle 8 MP). Um die restlichen beiden Pl\u00e4tze balgen sich aber noch rund ein halbes Dutzend Mannschaften.<\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R5: WeDa &#8211; SV Mattnetz 2:2<\/strong><\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R4: WeDa &#8211; Delmenhorster SK 2,5:1,5<\/strong><\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R3: WeDa &#8211; Empor Berlin 1,5:2,5<\/strong><\/p>\n<p>Stand: 8. September 2017 &#8211; 11:10 Uhr (R3: Live-\u00dcbertragung und Liveticker sind beendet.)<\/p>\n<p style=\"text-align: justify\"><strong>WeDa &#8211; Empor 1,5:2,5<\/strong> \u00a0 Kevin hat unentschieden gespielt durch Dauerschach nach 29. Dh5-g5+.<\/p>\n<figure id=\"attachment_5924\" aria-describedby=\"caption-attachment-5924\" style=\"width: 1478px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5924 size-full\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg\" alt=\"\" width=\"1478\" height=\"680\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg 1478w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-600x276.jpg 600w\" sizes=\"auto, (max-width: 1478px) 100vw, 1478px\" \/><figcaption id=\"caption-attachment-5924\" class=\"wp-caption-text\">Tats\u00e4chlich bietet Kevins Stellung noch ausgezeichnete Gewinnchancen, die aufzusp\u00fcren allerdings sehr schwer ist. Was hat Kevin nach der erzwungenen Zugfolge <strong>29. &#8230; Kf7 \u00a0 30. axb5 Txb5<\/strong> m\u00f6glicherweise nicht mehr gesehen oder falsch eingesch\u00e4tzt? Zum <a href=\"#Loesungsansatz\"><strong>L\u00f6sungsansatz<\/strong><\/a> &#8211; zur <strong><a href=\"#Loesung\">L\u00f6sung<\/a><\/strong> &#8230; (Bitte vorher mit &#8222;<em><strong>weiterlesen<\/strong><\/em>&#8220; den gesamten Beitrag aufrufen)<\/figcaption><\/figure>\n<hr \/>\n<p>Stand: 8. September 2017 &#8211; 10:05 Uhr<\/p>\n<p>WeDa &#8211; Empor 1:2 \u00a0 Hakob hat verloren.<\/p>\n<p>WeDa &#8211; Empor 1:1 \u00a0 Andranik hat verloren.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5920 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-4.jpg\" alt=\"\" width=\"1479\" height=\"681\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-4.jpg 1479w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-4-600x276.jpg 600w\" sizes=\"auto, (max-width: 1479px) 100vw, 1479px\" \/><\/p>\n<hr \/>\n<p>Stand: 8. September 2017 &#8211; 09:30 Uhr<\/p>\n<p>WeDa &#8211; Empor 1:0\u00a0\u00a0 Nam hat gewonnen &#8211; Matt im 16. Zug! Andranik steht auf Verlust. Hakobs Brett brennt &#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5917 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-3.jpg\" alt=\"\" width=\"1480\" height=\"678\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-3.jpg 1480w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-3-600x275.jpg 600w\" sizes=\"auto, (max-width: 1480px) 100vw, 1480px\" \/><\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R2: WeDa &#8211; L\u00fcbecker SV 2:2<br \/>\n <\/strong><\/p>\n<p>Stand: 7. September 2017 &#8211; 19:00 Uhr (R2: Live-\u00dcbertragung und Liveticker sind beendet.)<\/p>\n<p><strong>WeDa &#8211; L\u00fcbeck 2:2<\/strong> \u00a0 Kevin und Hakob haben unentschieden gespielt .<\/p>\n<p><a href=\"http:\/\/dvm.schnix.de\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5887 size-full\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-4.jpg\" alt=\"\" width=\"1469\" height=\"676\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-4.jpg 1469w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-4-600x276.jpg 600w\" sizes=\"auto, (max-width: 1469px) 100vw, 1469px\" \/><\/a><\/p>\n<hr \/>\n<p>Stand: 7. September 2017 &#8211; 17:45 Uhr<\/p>\n<p>WeDa &#8211; L\u00fcbeck 1:1 \u00a0 Kevins Zeitnot ist vorbei &#8211; die Stellung ausgeglichen. Hakob sollte gewinnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5883 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-3.jpg\" alt=\"\" width=\"1481\" height=\"679\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-3.jpg 1481w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-3-600x275.jpg 600w\" sizes=\"auto, (max-width: 1481px) 100vw, 1481px\" \/><\/p>\n<p>Stand: 7. September 2017 &#8211; 17:20 Uhr<\/p>\n<p>WeDa &#8211; L\u00fcbeck 1:1 \u00a0 Andranik hat verloren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5880 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-2.jpg\" alt=\"\" width=\"1478\" height=\"674\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-2.jpg 1478w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-2-600x274.jpg 600w\" sizes=\"auto, (max-width: 1478px) 100vw, 1478px\" \/><\/p>\n<hr \/>\n<p>Stand: 7. September 2017 &#8211; 17:15 Uhr<\/p>\n<p>WeDa &#8211; L\u00fcbeck 1:0\u00a0\u00a0 Nam hat gewonnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5878 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-1.jpg\" alt=\"\" width=\"1479\" height=\"677\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-1.jpg 1479w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R2-1-600x275.jpg 600w\" sizes=\"auto, (max-width: 1479px) 100vw, 1479px\" \/><\/p>\n<hr \/>\n<p><strong>NVM U14 &#8211; R1: WeDa &#8211; K\u00f6nigsspringer HH 4:0<br \/>\n <\/strong><\/p>\n<p>Stand: 7. September 2017 &#8211; 11:43 Uhr (R1: Live-\u00dcbertragung und Liveticker beendet.)<\/p>\n<p><strong>WeDa &#8211; K\u00f6Sp 4:0<\/strong>\u00a0\u00a0 Kevin hat gewonnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5865 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-5.jpg\" alt=\"\" width=\"1476\" height=\"676\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-5.jpg 1476w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-5-600x275.jpg 600w\" sizes=\"auto, (max-width: 1476px) 100vw, 1476px\" \/><\/p>\n<hr \/>\n<p>Stand: 7. September 2017 &#8211; 11:18 Uhr<\/p>\n<p>WeDa &#8211; K\u00f6Sp 3:0\u00a0\u00a0 Andranik hat gewonnen.<\/p>\n<p>WeDa &#8211; K\u00f6Sp 2:0\u00a0\u00a0 Hakob hat gewonnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5855 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-3.jpg\" alt=\"\" width=\"1477\" height=\"676\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-3.jpg 1477w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-3-600x275.jpg 600w\" sizes=\"auto, (max-width: 1477px) 100vw, 1477px\" \/><\/p>\n<hr \/>\n<p>Stand: 7. September 2017 &#8211; 10:48 Uhr<\/p>\n<p>WeDa &#8211; K\u00f6Sp 1:0\u00a0\u00a0 Nam hat gewonnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5849 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg.jpg\" alt=\"\" width=\"1480\" height=\"681\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg.jpg 1480w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-Magdeburg-600x276.jpg 600w\" sizes=\"auto, (max-width: 1480px) 100vw, 1480px\" \/><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong><a id=\"Loesungsansatz\"><\/a>L\u00f6sungsansatz<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5942\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w.jpg 728w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-600x600.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-32x32.jpg 32w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-50x50.jpg 50w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-64x64.jpg 64w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-96x96.jpg 96w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-128x128.jpg 128w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<p style=\"text-align: justify\">Bevor konkret auf die gewinntr\u00e4chtige(n) Zugfolge(n) eingegangen wird, sollen einige grunds\u00e4tzliche \u00dcberlegungen angestellt werden. Trotz der materiellen Gleichheit stellt sich das Gef\u00fchl ein, dass Schwarz schlechter steht: unsicherer K\u00f6nig, viele Bauerninseln, die Dame als eigentlich ungeeignete Blockadefigur. Wei\u00df hingegen hat vor allem (nur) ein (dringendes) Problem: Wie decke ich den Bauern auf c6? Wenn das zuverl\u00e4ssig gel\u00e4nge, sollte die Ausnutzung der schwarzen Schw\u00e4chen nur noch eine Frage der Technik sein. Leicht gesagt &#8211; schwer umzusetzen!<\/p>\n<p style=\"text-align: justify\">Denn zur gedanklichen Vorbereitung muss sich jetzt noch (Opfer-)Mut gesellen. Und davor scheut sich zun\u00e4chst erst einmal fast jeder; vor allem, wenn die Ernte nicht unmittelbar eingefahren werden kann. In einer <em>&#8222;Must-win&#8220;<\/em>-Situation geht das vielleicht einen Tick leichter, denn: <em>&#8222;Wenn ich nicht gewinne, ist ohnehin alles verloren!&#8220;<\/em><\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong><a id=\"Loesung\"><\/a>L\u00f6sung<\/strong><\/p>\n<p style=\"text-align: justify\">Der Schl\u00fcsselzug lautet <strong>31. Tc1!!<\/strong> Mit diesem (vergifteten) Bauernopferangebot werden die strukturellen Schw\u00e4chen von Schwarz offengelegt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5943\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1.jpg 728w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-600x600.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-32x32.jpg 32w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-50x50.jpg 50w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-64x64.jpg 64w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-96x96.jpg 96w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31w-1-128x128.jpg 128w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<p>Die Annahme des angebotenen Bauernopfers durch Schwarz wird mit dem stillen Zug <strong>32. Dh6!<\/strong> widerlegt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5945\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w.jpg 728w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-600x600.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-32x32.jpg 32w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-50x50.jpg 50w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-64x64.jpg 64w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-96x96.jpg 96w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-32w-128x128.jpg 128w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<p style=\"text-align: justify\">Die z\u00e4heste Verteidigung von Schwarz besteht tats\u00e4chlich im R\u00fcckzug des Turmes auf die Grundreihe, wonach Wei\u00df mittels b4-b5 den Freibauern ein zweites Mal deckt (<em>&#8222;Nehmen immer noch verboten!&#8220;<\/em>). Mit dem so befreiten wei\u00dfen Turm werden jetzt nach und nach die Bauerninseln von Schwarz attackiert und eine nach der anderen abger\u00e4umt. Viel Spa\u00df beim Ausarbeiten der Varianten!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5954 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s.jpg 728w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-600x600.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-32x32.jpg 32w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-50x50.jpg 50w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-64x64.jpg 64w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-96x96.jpg 96w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5-KR-vs-DS-31s-128x128.jpg 128w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Und wieder eine Live-\u00dcbertragung\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Turnierseite \u00a0\u00a0\u00a0 \u00a0 Hendriks WeDa&#8211;Rundenberichte Zum Abschluss ein Sieg gegen den Setzlistenersten und k\u00fcnftigen JBL-Konkurrenten bringt den 4. Platz in der Endtabelle. Der SV Empor Berlin &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/\" class=\"more-link\"><span class=\"screen-reader-text\">NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[20,32],"tags":[],"coauthors":[50],"class_list":["post-5848","post","type-post","status-publish","format-standard","hentry","category-jugend","category-weda-unterwegs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Und wieder eine Live-\u00dcbertragung\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Turnierseite \u00a0\u00a0\u00a0 \u00a0 Hendriks WeDa&#8211;Rundenberichte Zum Abschluss ein Sieg gegen den Setzlistenersten und k\u00fcnftigen JBL-Konkurrenten bringt den 4. Platz in der Endtabelle. Der SV Empor Berlin &hellip; NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!) weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-03T10:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-10T15:31:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg\" \/>\n<meta name=\"author\" content=\"Christian Greiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Greiser\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christian Greiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/\"},\"author\":{\"name\":\"Christian Greiser\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\"},\"headline\":\"NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)\",\"datePublished\":\"2017-09-03T10:00:25+00:00\",\"dateModified\":\"2017-09-10T15:31:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/\"},\"wordCount\":1065,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-NVM-R3-5.jpg\",\"articleSection\":[\"Jugend\",\"WeDa unterwegs\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/\",\"name\":\"NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-NVM-R3-5.jpg\",\"datePublished\":\"2017-09-03T10:00:25+00:00\",\"dateModified\":\"2017-09-10T15:31:05+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#primaryimage\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-NVM-R3-5.jpg\",\"contentUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-NVM-R3-5.jpg\",\"width\":1478,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2017\\\/09\\\/nvm-u14-live-partien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\",\"name\":\"Christian Greiser\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/christian_greiser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/","og_locale":"de_DE","og_type":"article","og_title":"NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.","og_description":"Und wieder eine Live-\u00dcbertragung\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Turnierseite \u00a0\u00a0\u00a0 \u00a0 Hendriks WeDa&#8211;Rundenberichte Zum Abschluss ein Sieg gegen den Setzlistenersten und k\u00fcnftigen JBL-Konkurrenten bringt den 4. Platz in der Endtabelle. Der SV Empor Berlin &hellip; NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!) weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2017-09-03T10:00:25+00:00","article_modified_time":"2017-09-10T15:31:05+00:00","og_image":[{"url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg","type":"","width":"","height":""}],"author":"Christian Greiser","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Greiser","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten","Written by":"Christian Greiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/"},"author":{"name":"Christian Greiser","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946"},"headline":"NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)","datePublished":"2017-09-03T10:00:25+00:00","dateModified":"2017-09-10T15:31:05+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/"},"wordCount":1065,"commentCount":0,"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg","articleSection":["Jugend","WeDa unterwegs"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/","name":"NVM U14 - R7: WeDa - Reideburg 2,5:1,5 (Finale furioso!) - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"primaryImageOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#primaryimage"},"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg","datePublished":"2017-09-03T10:00:25+00:00","dateModified":"2017-09-10T15:31:05+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#primaryimage","url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg","contentUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2017\/09\/2017-NVM-R3-5.jpg","width":1478,"height":680},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2017\/09\/nvm-u14-live-partien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"NVM U14 &#8211; R7: WeDa &#8211; Reideburg 2,5:1,5 (Finale furioso!)"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946","name":"Christian Greiser","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/christian_greiser\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/5848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=5848"}],"version-history":[{"count":11,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/5848\/revisions"}],"predecessor-version":[{"id":6043,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/5848\/revisions\/6043"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=5848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=5848"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=5848"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=5848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}