{"id":34304,"date":"2026-02-10T10:00:42","date_gmt":"2026-02-10T09:00:42","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=34304"},"modified":"2026-02-10T10:17:07","modified_gmt":"2026-02-10T09:17:07","slug":"freitag-der-13-im-doppelpack-im-februar-und-maerz","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/","title":{"rendered":"Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz"},"content":{"rendered":"<p>Liebe Schachfreunde,<\/p>\n<p>das Jahr 2026 ist etwas ganz Besonderes. Zum einen gibt es in diesem Jahr gleich <strong>drei<\/strong> Freitage, die auf den 13. des Monats fallen. Los geht es gleich mit einem Doppelpack, n\u00e4mlich am <strong>Freitag, den 13. Februar <\/strong>und am<strong> 13. M\u00e4rz<\/strong>.<\/p>\n<p>Da der SC WEISSE DAME e.V. au\u00dferdem im Jahr 2026 sein <strong>75-j\u00e4hriges Jubil\u00e4um<\/strong> der Vereinsgr\u00fcndung feiern wird, wurde aus diesem Anlass der Preisfonds merklich angehoben. Das Startgeld bleibt allerdings wie gewohnt bei lediglich 5 EUR.<\/p>\n<p>F\u00fcr alle Vereinsmitglieder ist au\u00dferdem zu beachten, dass diese Turniere zus\u00e4tzlich auch als 1. und 2. Wertungsturnier f\u00fcr die <strong>Clubschnellschachmeisterschaft<\/strong> gewertet werden und kein Startgeld erhoben wird.<\/p>\n<div>Wer wird sich als n\u00e4chstes in die lange <a href=\"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/freitag-der-13\/\"><strong>Siegerliste<\/strong><\/a> des Turniers eintragen? Wir freuen uns auf viele Teilnehmer aus dem Verein und von anderswo.\u00a0<\/div>\n<div>\u00a0<\/div>\n<p>Die <strong>vollst\u00e4ndige Ausschreibung<\/strong> findet sich im folgenden Text:<!--more--><\/p>\n<hr \/>\n<h6 style=\"text-align: center;\"><strong><span dir=\"ltr\" role=\"presentation\">Offene Schnellschach-Turniere<\/span><\/strong><br role=\"presentation\" \/><br \/>\n<strong><span dir=\"ltr\" role=\"presentation\">f\u00fcr Einzelspieler<\/span><span dir=\"ltr\" role=\"presentation\">:<\/span><span dir=\"ltr\" role=\"presentation\">innen<\/span><\/strong><br role=\"presentation\" \/><br \/>\n<strong><span dir=\"ltr\" role=\"presentation\">\u201eFreitag der 13.\u201c<\/span><\/strong><br role=\"presentation\" \/><br \/>\n<strong><span dir=\"ltr\" role=\"presentation\">am 13.02.2026 und 13.03.2026<\/span><\/strong><\/h6>\n<p class=\"textLayer\" tabindex=\"0\" data-main-rotation=\"0\"><strong><span dir=\"ltr\" role=\"presentation\">Modus:<br \/>\n<\/span><\/strong><span dir=\"ltr\" role=\"presentation\">Sieben Runden Schweizer System nach FIDE-Schnellschachregeln (Ausnahme: erster <\/span><span dir=\"ltr\" role=\"presentation\">regelwidriger Zug verliert die Partie)<br \/>\n<\/span><span dir=\"ltr\" role=\"presentation\">Begrenzte Teilnehmerkapazit\u00e4t \u2013 max. 50 Teilnehmer:innen m\u00f6glich (ma\u00dfgeblich ist die <\/span><span dir=\"ltr\" role=\"presentation\">Reihenfolge der Anmeldung vor Ort)<br \/>\n<span style=\"color: #ff0000;\">Die beiden Turniere z\u00e4hlen au\u00dferdem als 1. bzw. 2. Wertungsturnier der Clubschnellschachmeisterschaft 2026.<\/span><\/span><\/p>\n<p class=\"textLayer\" tabindex=\"0\" data-main-rotation=\"0\"><strong><span dir=\"ltr\" role=\"presentation\">Bedenkzeit:<br \/>\n<\/span><\/strong><span dir=\"ltr\" role=\"presentation\">10 Minuten plus 3 Sekunden\/Zug pro Spieler und Partie<\/span><\/p>\n<p class=\"textLayer\" tabindex=\"0\" data-main-rotation=\"0\"><strong><span dir=\"ltr\" role=\"presentation\">Startgeld:<br \/>\n<\/span><\/strong><strong><span dir=\"ltr\" role=\"presentation\">5 \u20ac<\/span><\/strong> <span dir=\"ltr\" role=\"presentation\">(Barzahlung bei der Anmeldung f\u00fcr Nichtmitglieder des SC Weisse Dame e.V.)<\/span><\/p>\n<p class=\"textLayer\" tabindex=\"0\" data-main-rotation=\"0\"><strong><span dir=\"ltr\" role=\"presentation\">Preisfonds:<br \/>\n<\/span><\/strong><span dir=\"ltr\" style=\"color: #ff0000;\" role=\"presentation\">Aus Anlass des 75-j\u00e4hrigen Bestehens der Weissen Dame wird der Preisfonds erh\u00f6ht.<br \/>\n<\/span><strong><span dir=\"ltr\" role=\"presentation\">75 \u20ac \/ 60 \u20ac \/ 45 \u20ac \/ 30 \u20ac<br \/>\n<\/span><\/strong><span dir=\"ltr\" role=\"presentation\">Rating-Sonderpreise: <\/span><strong><span dir=\"ltr\" role=\"presentation\">je<\/span> <span dir=\"ltr\" role=\"presentation\">30<\/span> <span dir=\"ltr\" role=\"presentation\">\u20ac<\/span><\/strong> <span dir=\"ltr\" role=\"presentation\">f\u00fcr<\/span> <span dir=\"ltr\" role=\"presentation\">DWZ\/ELO &lt; 2000 \/ &lt; 1750<\/span> <span dir=\"ltr\" role=\"presentation\">\/ &lt; 1500<br \/>\n<\/span><span dir=\"ltr\" role=\"presentation\">Preisverteilung nach Endrangliste (kein Hort-System), pro Spieler max. ein Preis<\/span><\/p>\n<p class=\"textLayer\" tabindex=\"0\" data-main-rotation=\"0\"><strong><span dir=\"ltr\" role=\"presentation\">Zeitplan:<br \/>\n<\/span><\/strong><span dir=\"ltr\" role=\"presentation\">Anmeldeschluss:<\/span> <span dir=\"ltr\" role=\"presentation\">19:15 Uhr<br \/>\nTurnierbeginn. ca. 19.30 Uhr<br \/>\n<\/span><span dir=\"ltr\" role=\"presentation\">Preisverleihung:<\/span> <span dir=\"ltr\" role=\"presentation\">ca. 23:00 Uhr<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Schachfreunde, das Jahr 2026 ist etwas ganz Besonderes. Zum einen gibt es in diesem Jahr gleich drei Freitage, die auf den 13. des Monats fallen. Los geht es gleich &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/\" class=\"more-link\"><span class=\"screen-reader-text\">Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[29,9],"tags":[],"coauthors":[60],"class_list":["post-34304","post","type-post","status-publish","format-standard","hentry","category-freitag-der-13","category-schnellschach"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Liebe Schachfreunde, das Jahr 2026 ist etwas ganz Besonderes. Zum einen gibt es in diesem Jahr gleich drei Freitage, die auf den 13. des Monats fallen. Los geht es gleich &hellip; Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T09:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T09:17:07+00:00\" \/>\n<meta name=\"author\" content=\"Ralf Mohrmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ralf Mohrmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Ralf Mohrmann\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/\"},\"author\":{\"name\":\"Ralf Mohrmann\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/335f24c442da6b887035af6993fb566f\"},\"headline\":\"Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz\",\"datePublished\":\"2026-02-10T09:00:42+00:00\",\"dateModified\":\"2026-02-10T09:17:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/\"},\"wordCount\":271,\"articleSection\":[\"Freitag der 13.\",\"Schnellschach\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/\",\"name\":\"Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2026-02-10T09:00:42+00:00\",\"dateModified\":\"2026-02-10T09:17:07+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/335f24c442da6b887035af6993fb566f\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2026\\\/02\\\/freitag-der-13-im-doppelpack-im-februar-und-maerz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/335f24c442da6b887035af6993fb566f\",\"name\":\"Ralf Mohrmann\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/ralf_mohrmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/","og_locale":"de_DE","og_type":"article","og_title":"Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.","og_description":"Liebe Schachfreunde, das Jahr 2026 ist etwas ganz Besonderes. Zum einen gibt es in diesem Jahr gleich drei Freitage, die auf den 13. des Monats fallen. Los geht es gleich &hellip; Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2026-02-10T09:00:42+00:00","article_modified_time":"2026-02-10T09:17:07+00:00","author":"Ralf Mohrmann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ralf Mohrmann","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten","Written by":"Ralf Mohrmann"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/"},"author":{"name":"Ralf Mohrmann","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/335f24c442da6b887035af6993fb566f"},"headline":"Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz","datePublished":"2026-02-10T09:00:42+00:00","dateModified":"2026-02-10T09:17:07+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/"},"wordCount":271,"articleSection":["Freitag der 13.","Schnellschach"],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/","name":"Freitag der 13. im Doppelpack - im Februar und M\u00e4rz - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2026-02-10T09:00:42+00:00","dateModified":"2026-02-10T09:17:07+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/335f24c442da6b887035af6993fb566f"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2026\/02\/freitag-der-13-im-doppelpack-im-februar-und-maerz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Freitag der 13. im Doppelpack &#8211; im Februar und M\u00e4rz"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/335f24c442da6b887035af6993fb566f","name":"Ralf Mohrmann","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/ralf_mohrmann\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/34304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=34304"}],"version-history":[{"count":8,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/34304\/revisions"}],"predecessor-version":[{"id":34316,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/34304\/revisions\/34316"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=34304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=34304"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=34304"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=34304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}