{"id":33732,"date":"2025-11-30T14:42:04","date_gmt":"2025-11-30T13:42:04","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=33732"},"modified":"2025-12-05T23:58:38","modified_gmt":"2025-12-05T22:58:38","slug":"cm-r4","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/","title":{"rendered":"Clubmeisterschaft \u2013 Vierte Runde"},"content":{"rendered":"<p>Hier die Paarungen f\u00fcr die vierte Runde der Clubmeisterschaft am n\u00e4chsten Freitag, dem 5. 12.:<\/p>\n<div style=\"line-height:1.0;overflow-y:hidden;display:grid;grid-template-columns:1fr auto 1fr 1fr auto 1fr;grid-template-rows:auto;overflow-x:auto;white-space:nowrap;border-right:1px solid #808080;border-bottom:1px solid #808080;\">\n<div style=\"background:#cae590;font-weight:bold;border-top:1px solid #808080;border-bottom:1px solid #808080;display:flex;align-items:center;height:3em;justify-content:center;grid-column:1 \/ 4;text-align:center;display:flex;align-items:center;justify-content:center;border-left:1px solid #808080;\">A-Klasse<\/div>\n<div style=\"background:#cae590;font-weight:bold;border-top:1px solid #808080;border-bottom:1px solid #808080;display:flex;align-items:center;height:3em;justify-content:center;grid-column:4 \/ 7;text-align:center;display:flex;align-items:center;justify-content:center;\">B-Klasse<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Oliver<br \/><\/small>H\u00f6lscher<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">0-1<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Ingo<br \/><\/small>Abraham<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Dennis<br \/><\/small>Bertuch<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">1-0<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Laurenz<br \/><\/small>Preissner<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Hendrik<br \/><\/small>M\u00f6ller<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00d7<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Carsten<br \/><\/small>Miemietz<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Harald<br \/><\/small>Gr\u00fcnwald<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00bd-\u00bd<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Max<br \/><\/small>Hoyer<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Ralf<br \/><\/small>Mohrmann<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">0-1<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Thorsten<br \/><\/small>Gro\u00df<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Oliver<br \/><\/small>Otterson<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00bd-\u00bd<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Jakob<br \/><\/small>Grimm<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Christian<br \/><\/small>Greiser<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">1-0<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Heinz<br \/><\/small>Wirth<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Dawid<br \/><\/small>Lewicki<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">1-0<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Mohamed<br \/><\/small>Elkhedr<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Ingo<br \/><\/small>Abraham<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">0-1<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Sebastian<br \/><\/small>Bender<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Mathias<br \/><\/small>Tag<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">0-1<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Nicolas<br \/><\/small>Bureik<\/div>\n<div style=\"background:#cae590;font-weight:bold;border-top:1px solid #808080;border-bottom:1px solid #808080;display:flex;align-items:center;height:3em;justify-content:center;grid-column:1 \/ 4;text-align:center;display:flex;align-items:center;justify-content:center;border-left:1px solid #808080;\">C-Klasse<\/div>\n<div style=\"background:#cae590;font-weight:bold;border-top:1px solid #808080;border-bottom:1px solid #808080;display:flex;align-items:center;height:3em;justify-content:center;grid-column:4 \/ 7;text-align:center;display:flex;align-items:center;justify-content:center;\">D-Klasse<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Simon<br \/><\/small>Gemen<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00d7<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Lukas<br \/><\/small>Risse<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Wesley<br \/><\/small>Miemietz<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">1-0<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Namia<br \/><\/small>Stange<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Niklas<br \/><\/small>Tonsen<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00d7<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Beeri<br \/><\/small>Nisan<\/div>\n<div style=\"background:#9FBFDF;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Anahit<br \/><\/small>Babadshanjan<\/div>\n<div style=\"background:#9FBFDF;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">0-1<\/div>\n<div style=\"background:#9FBFDF;height:2em;text-align:left  ;\"><small>Gennesaret<br \/><\/small>Tjusila<\/div>\n<div style=\"background:#B7CFE7;height:2em;border-left:1px solid #808080;text-align:right ;\"><small>Reiner<br \/><\/small>Linkies<\/div>\n<div style=\"background:#B7CFE7;height:2em;display:flex;align-items:center;justify-content:center;text-align:center;padding-left:1.5em;padding-right:1.5em;\">\u00bd-\u00bd<\/div>\n<div style=\"background:#B7CFE7;height:2em;text-align:left  ;\"><small>Ben<br \/><\/small>Schumacher<\/div>\n<div style=\"background:#B7CFE7;height:2em;grid-column:4 \/ 7;text-align:center;display:flex;align-items:center;justify-content:center;border-left:1px solid #808080;\">Bhavadeep Nettem spielfrei<\/div>\n<div style=\"background:#9FBFDF;height:2em;grid-column:1 \/ 4;text-align:center;display:flex;align-items:center;justify-content:center;border-left:1px solid #808080;\">J\u00f6rn Grotjahn spielfrei<\/div>\n<div style=\"background:#9FBFDF;height:2em;grid-column:4 \/ 7;text-align:center;border-left:1px solid #808080;\"><small>&nbsp;<br \/><\/small>&nbsp;<\/div>\n<\/div>\n<p>Bei der Partie Abraham \u00ad\u2013 Bender handelt es sich um eine Nachholpartie aus Runde 3. Die Partie H\u00f6lscher \u2013 Abraham wurde am vorherigen Freitag vorgezogen. Die Partie Tonsen \u2013 Nisan muss verlegt werden. Spielbeginn wie immer um 19:15. Mehr Informationen auf der <a href=\"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubmeisterschaft\/clubmeisterschaft-2026\/\">Turnierseite<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier die Paarungen f\u00fcr die vierte Runde der Clubmeisterschaft am n\u00e4chsten Freitag, dem 5. 12.: A-Klasse B-Klasse OliverH\u00f6lscher 0-1 IngoAbraham DennisBertuch 1-0 LaurenzPreissner HendrikM\u00f6ller \u00d7 CarstenMiemietz HaraldGr\u00fcnwald \u00bd-\u00bd MaxHoyer RalfMohrmann &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/\" class=\"more-link\"><span class=\"screen-reader-text\">Clubmeisterschaft \u2013 Vierte Runde<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[4],"tags":[],"coauthors":[194],"class_list":["post-33732","post","type-post","status-publish","format-standard","hentry","category-clubmeisterschaft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.\" \/>\n<meta property=\"og:description\" content=\"Hier die Paarungen f\u00fcr die vierte Runde der Clubmeisterschaft am n\u00e4chsten Freitag, dem 5. 12.: A-Klasse B-Klasse OliverH\u00f6lscher 0-1 IngoAbraham DennisBertuch 1-0 LaurenzPreissner HendrikM\u00f6ller \u00d7 CarstenMiemietz HaraldGr\u00fcnwald \u00bd-\u00bd MaxHoyer RalfMohrmann &hellip; Clubmeisterschaft \u2013 Vierte Runde weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-30T13:42:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T22:58:38+00:00\" \/>\n<meta name=\"author\" content=\"Dennis Bertuch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Bertuch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Dennis Bertuch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/\"},\"author\":{\"name\":\"Dennis Bertuch\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/3de788f23977491c5edd43bf2e82f879\"},\"headline\":\"Clubmeisterschaft \u2013 Vierte Runde\",\"datePublished\":\"2025-11-30T13:42:04+00:00\",\"dateModified\":\"2025-12-05T22:58:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/\"},\"wordCount\":145,\"articleSection\":[\"Clubmeisterschaft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/\",\"name\":\"Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2025-11-30T13:42:04+00:00\",\"dateModified\":\"2025-12-05T22:58:38+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/3de788f23977491c5edd43bf2e82f879\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2025\\\/11\\\/cm-r4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clubmeisterschaft \u2013 Vierte Runde\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e. V.\",\"description\":\"Herzlich Willkommen!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/3de788f23977491c5edd43bf2e82f879\",\"name\":\"Dennis Bertuch\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/denber167\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/","og_locale":"de_DE","og_type":"article","og_title":"Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.","og_description":"Hier die Paarungen f\u00fcr die vierte Runde der Clubmeisterschaft am n\u00e4chsten Freitag, dem 5. 12.: A-Klasse B-Klasse OliverH\u00f6lscher 0-1 IngoAbraham DennisBertuch 1-0 LaurenzPreissner HendrikM\u00f6ller \u00d7 CarstenMiemietz HaraldGr\u00fcnwald \u00bd-\u00bd MaxHoyer RalfMohrmann &hellip; Clubmeisterschaft \u2013 Vierte Runde weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/","og_site_name":"SC Weisse Dame e. V.","article_published_time":"2025-11-30T13:42:04+00:00","article_modified_time":"2025-12-05T22:58:38+00:00","author":"Dennis Bertuch","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dennis Bertuch","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Dennis Bertuch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/"},"author":{"name":"Dennis Bertuch","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/3de788f23977491c5edd43bf2e82f879"},"headline":"Clubmeisterschaft \u2013 Vierte Runde","datePublished":"2025-11-30T13:42:04+00:00","dateModified":"2025-12-05T22:58:38+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/"},"wordCount":145,"articleSection":["Clubmeisterschaft"],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/","name":"Clubmeisterschaft \u2013 Vierte Runde - SC Weisse Dame e. V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2025-11-30T13:42:04+00:00","dateModified":"2025-12-05T22:58:38+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/3de788f23977491c5edd43bf2e82f879"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2025\/11\/cm-r4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Clubmeisterschaft \u2013 Vierte Runde"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e. V.","description":"Herzlich Willkommen!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/3de788f23977491c5edd43bf2e82f879","name":"Dennis Bertuch","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/denber167\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/33732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=33732"}],"version-history":[{"count":9,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/33732\/revisions"}],"predecessor-version":[{"id":33756,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/33732\/revisions\/33756"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=33732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=33732"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=33732"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=33732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}