{"id":22806,"date":"2022-03-21T07:30:52","date_gmt":"2022-03-21T06:30:52","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=22806"},"modified":"2022-03-21T07:48:22","modified_gmt":"2022-03-21T06:48:22","slug":"fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/","title":{"rendered":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation"},"content":{"rendered":"<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Liebe Mitglieder des SC Weisse Dame,<\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">im Auftrag des Vorstands m\u00f6chte ich \u00fcber die aktuell wichtigsten Entwicklungen in unserem Verein im Bereich des Schachspiels f\u00fcr Erwachsene informieren.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Interner Spielbetrieb:<\/b><\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">In den letzten Wochen waren wir corona-und organisationsbedingt auf einen 2-Wochen-Rhythmus ausgewichen. Diesen werden wir noch bis Ostern aufrechterhalten. Das bedeutet, dass am <b>25.3.<\/b> um 19:30 Uhr ein Schnellturnier stattfindet sowie am <b>8.4. <\/b>ein weiterer Vortrag mit Atila Figura,\u00a0 dass aber am 1.4. kein Spielbetrieb erfolgt und auch am 15.4. (Karfreitag) kein Spielabend stattfindet. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Der Zugang zum internen Spielbetrieb erfolgt <b>bis Ende M\u00e4rz noch unter 2G+-Bedingungen, ab April unter 3 G-Bedingungen<\/b> (wer also nicht geimpft oder genesen ist, kann ab dann trotzdem kommen, wenn er einen tagesaktuellen Testnachweis erbringt), sofern die Beschr\u00e4nkungen dann nicht sogar in G\u00e4nze fallen. Um gr\u00f6\u00dftm\u00f6gliche Sicherheit an den Spielabenden zu erm\u00f6glichen, w\u00fcnschen wir uns weiterhin, dass sich auch die geboosterten und genesenen Schachfreunde auf freiwilliger Basis testen, zumal die nach wie vor steigenden Inzidenzzahlen zur bleibenden Vorsicht gemahnen. Hinsichtlich der Hygienekonzepte, die dann auch immer auf unserer Homepage zu finden sind, danke ich in besonderer Weise Heinz Uhl, der sich hier sehr verdient gemacht hat.<\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><i><b>Ab dem 22.04.22<\/b><\/i> wollen wir dann wieder einen <i><b>w\u00f6chentlichen Spielabend<\/b><\/i> anbieten. Wegen der Osterferien beginnen wir am 22.4. mit geselligem freien Spiel, ab dem 29.4. soll es dann jeweils zum Monatsende wie gehabt im Wechsel ein Blitz- oder Schnellturnier geben. Aufgrund der schlechten mittelfristigen Planbarkeit wollen wir diese Turniere aber noch nicht wieder als Meisterschaften durchf\u00fchren. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Ab dem <b>6.5.22 <\/b>wollen wir es aber wagen, den <b>Otto-Christ-Pokal<\/b> (Clubpokal) als Teil des offiziellen Meisterschaftsprogramms wieder aufleben zu lassen. Den dezidierten Modus werden wir noch genauer \u00fcberlegen; eine Ausschreibung wird dann rechtzeitig versandt. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Ein gesonderter Dank ergeht an dieser Stelle an die kleine Vorbereitungsgruppe (T. Meyer, R. Radke, H. Wirth, flankiert von R. Mohrmann) f\u00fcr den internen Spielbetrieb, der wir in den letzten Wochen den einen oder anderen Impuls zu verdanken hatten.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Lichess:<\/b><\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Nach wie vor besteht die M\u00f6glichkeit, sich online im Rahmen der Q-Liga f\u00fcr unseren Verein zu engagieren. Gerade ist es besonders g\u00fcnstig, da die Weisse Dame sensationell in Runde 200 in die dritte Liga aufgestiegen und diese nun auch sogleich best\u00e4tigt hat (und viel fehlte nicht zum historischen Aufstieg in Liga 2!). Ein herzliches Dankesch\u00f6n an dieser Stelle den Admins und Berichterstattern, allen voran an WeDaChris, der mit Runde 200 auf dem H\u00f6hepunkt seines Schaffens die Berichterstattung mit dem kr\u00f6nenden Aufstieg beendete.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Externer Spielbetrieb: <\/b><\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Abgesehen von der vierten Mannschaft, die wir zur\u00fcckziehen mussten und quasi mit der dritten Mannschaft verschmolzen haben, sind noch alle Mannschaften (1,2,3,5,6) in der BMM am Start. Inzwischen fand eine zweite Runde statt, die n\u00e4chste folgt jetzt am 27.3., dann die weiteren Runden von Mai bis Mitte Juli. Es gilt <i>aktuell <\/i>(f\u00fcr gew\u00f6hnlich) <b>3 G <\/b>als Teilnahmevoraussetzung. Nat\u00fcrlich ist das gesamte BMM-Geschehen alles andere als normal zu bezeichnen, aber zumindest zeichnet sich ab, dass die Saison regul\u00e4r (zu Ende) gespielt werden kann. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Ein Dank sei an dieser Stelle speziell an Martin Kaiser, der im Vorstand den externen Spielbetrieb organisiert, sowie den Mannschaftsleitungen gesagt.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Jahreshauptversammlung \/ Grillfest<\/b><\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Die diesj\u00e4hrige Jahreshauptversammlung werden wir voraussichtlich am <b>1.7.22<\/b> durchf\u00fchren (sofern eine rechtliche Pr\u00fcfung ergibt, dass wir coronabedingt von der satzungsbedingt vorgegebenen Durchf\u00fchrung im zweiten Quartal absehen k\u00f6nnen; ansonsten weichen wir auf den 17.6. aus). Diese wird nach derzeitigem Stand ausschlie\u00dflich analog (also auch nicht hybrid) erfolgen. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Bereits jetzt sind alle Mitglieder aufgerufen, sich zu \u00fcberlegen, sich k\u00fcnftig im Rahmen der Vorstandsarbeit zu engagieren. Bei Interesse an einer Mitarbeit\/einem Amt (gerne auch des 1. Vorsitzenden &#8230;) bitte ich um Kontaktaufnahme.<\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Anders als sonst wollen wir diesmal vor der JHV ein Grillfest durchf\u00fchren, mit dem wir auch unser <i><b>70-j\u00e4hriges Jubil\u00e4um<\/b><\/i> nachfeiern wollen. <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Ukraine-Engagement<\/b><\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Selbstverst\u00e4ndlich wollen auch wir uns als Schachverein mit den uns gegebenen Mitteln f\u00fcr Frieden in der Ukraine und Hilfe f\u00fcr Menschen, die vor dem Krieg fliehen m\u00fcssen, einsetzen, so wie unser Verein das bereits in der Fl\u00fcchtlingskrise unter Beweis gestellt hat. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Die Idee ist, dass wir Kontakt zu geeigneten Fl\u00fcchtlingseinrichtungen in unserem Bezirk oder angrenzenden Bezirken aufnehmen und dort &#8211; vielleicht in Form einer Partnerschaft &#8211; Angebote vorhalten. Das kann vom Verleih von Schachspielen bis hin zu gemeinsamen Spiel-und Kennenlernabenden vor Ort, Einladungen in den Verein, gemeinsamen Ausfl\u00fcgen und sich daraus ergebenden l\u00e4ngerfristigen individuellen Kontakten reichen. Dabei lassen wir uns auch von dem Gedanken leiten, dass nach einer ersten Phase, in der es vor allem um Ankommen, Verteilung, Existenzsicherung geht, sicherlich auch eine Phase folgen wird, in der die l\u00e4ngerfristig in Einrichtungen verbleibenden Menschen froh \u00fcber Kontakte, Abwechslung und M\u00f6glichkeiten der wachsenden Integration sein werden. Gerade in dieser Phase werden wir sicherlich segensreich und ganz konkret mitwirken k\u00f6nnen. Dabei sind wir uns dessen auch bewusst, dass das Schachspiel vor dem Hintergrund der fr\u00fcheren sowjetischen Schachschule gerade auch f\u00fcr Menschen in der Ukraine eine besondere Rolle spielen d\u00fcrfte und dass Schach an sich bereits eine international verbindende Sprache darstellt, \u00fcber die man in Kontakt kommen kann. Sollten sich im n\u00e4heren Umfeld unseres Spielortes im \u00dcbrigen keine geeigneten Kooperationsm\u00f6glichkeiten auftun, k\u00f6nnte ich auch \u00fcber meinen Dienstgeber, den Caritasverband, zu einer binnen 2 Tagen neugeschaffenen Einrichtung mit \u00fcber 100 Pl\u00e4tzen im Prenzlauer Berg den Kontakt herstellen. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>Wer perspektivisch Interesse hat, sich auf die eine oder andere Weise in diesem Rahmen zu engagieren, der schreibe bitte an mich (<a href=\"mailto:1.Vorsitzender@sc-weisse-dame.de\">1.Vorsitzender@sc-weisse-dame.de<\/a>) und in cc den zweiten Vorsitzenden (<a href=\"mailto:2.Vorsitzender@sc-weisse-dame.de\">2.Vorsitzender@sc-weisse-dame.de<\/a>) eine Mail, m\u00f6glichst bis zum 23.3. <\/b><\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Wir werden dann &#8211; voraussichtlich per Zoom &#8211; ein <\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>erstes Brainstorm-Treffen<\/b><\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"> koordinieren. Dieses k\u00f6nnte evtl. bereits am <\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><b>1.4.<\/b><\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"> (anstelle des Spielabends) erfolgen.<\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Wie k\u00f6nnen wir sonst noch helfen? Hier sei zun\u00e4chst an den <a href=\"https:\/\/www.schachbund.de\/ukraine-hilfe.html\">Aufruf des DSB<\/a> verwiesen: Dort kann man auch spenden und sich, speziell auch f\u00fcr ukrainische Schachspieler*innen und ihre Familien, als Quartiergeber registrieren lassen. <\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Konkret erreichte uns zudem \u00fcber unser Mitglied Felix Zesch, der bereits eine ukrainische Familie beherbergt, die Anfrage des ukrainischen U-10-Meisters und seiner Familie nach Unterbringung. <span style=\"color: #000000;\">Es handelt sich um den ukrainischen U10-Meister, seine Gro\u00dfmutter, Mutter und seinen kleineren Bruder, die sich zum Zeitpunkt der Anfrage noch in Polen aufhielten. Sollte jemand zur Aufnahme bereit sein, bitte ich um R\u00fcckmeldung an mich, ich w\u00fcrde dann den Kontakt zum DSB weitergeben.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Sicherlich werden unsere Mitglieder viele Fragen haben, wie sie helfen k\u00f6nnen, wie die aktuellen Regelungen sind u.v.m. Mein Dienstgeber, der Caritasverband Berlin,\u00a0 hat hierf\u00fcr gleich im Startbereich seiner Homepage umfangreiche Informationen zusammengestellt <a href=\"https:\/\/www.caritas-berlin.de\/\">https:\/\/www.caritas-berlin.de\/<\/a>, auf die ich hier der Einfachheit weiterverweise. Dort finden sich nat\u00fcrlich auch weitergehende Spendenm\u00f6glichkeiten (Geld-, Zeit- und Sachspenden), u.a. auch f\u00fcr das besagte neuer\u00f6ffnete Heim oder das ebenfalls neuer\u00f6ffnete Waisenhaus f\u00fcr ukrainische Kinder in Alt Buchhorst. Dies sind selbstverst\u00e4ndlich nur Beispiele f\u00fcr ein m\u00f6gliches Engagement; es sei mir verziehen, wenn ich in diesem Rahmen gezielt auf meinen dienstlichen Kontext abhebe- dies erfolgt einfach auch aus dem Impuls heraus, dass ich diese Angebote und Akteure im Hintergrund konkret kenne und selber einzusch\u00e4tzen vermag. <\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Im Namen des Vorstandes w\u00fcrde ich mich freuen, wenn sich m\u00f6glichst viele Mitglieder im Rahmen der aktuellen krisenhaften Entwicklungen f\u00fcr Frieden und Mitmenschlichkeit engagieren und Solidarit\u00e4t mit dem ukrainischen Volk zeigen. Schach soll dabei der V\u00f6lkerverst\u00e4ndigung dienen. Dies schlie\u00dft selbstverst\u00e4ndlich auch das russische Volk mit ein, ohne das es jetzt und k\u00fcnftig keinen Frieden geben kann und wird. Mir ist wichtig zu betonen, dass wir auch weiterhin offen f\u00fcr alle Schachspieler*innen unabh\u00e4ngig von ihrer Staatsangeh\u00f6rigkeit und Nationalit\u00e4t sind und bleiben. Dies schlie\u00dft nicht aus, dass auch internationale Boykotts im sportlichen\/schachsportlichen Bereich, insbesondere wenn es um K\u00e4mpfe im Profi-Bereich mit Medaillenrang, Preisgelder o.\u00e4. geht, unsere Unterst\u00fctzung finden. Gerade im Amateurbereich ist es jedoch wichtig, das v\u00f6lkerverbindende Element des Schachspiels zu pflegen. <\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Mit diesen Gedanken m\u00f6chte ich allen unseren Mitgliedern einen sch\u00f6nen Start in den Fr\u00fchling und eine friedliche sowie erf\u00fcllte Zeit w\u00fcnschen!<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Herzlich gr\u00fc\u00dft im Namen des gesamten Vorstands<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">Kai-Gerrit Venske<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\">1. Vorsitzender<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Mitglieder des SC Weisse Dame, im Auftrag des Vorstands m\u00f6chte ich \u00fcber die aktuell wichtigsten Entwicklungen in unserem Verein im Bereich des Schachspiels f\u00fcr Erwachsene informieren. &nbsp; Interner Spielbetrieb: &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/\" class=\"more-link\"><span class=\"screen-reader-text\">Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[77],"tags":[],"coauthors":[64],"class_list":["post-22806","post","type-post","status-publish","format-standard","hentry","category-organisatorisches"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Liebe Mitglieder des SC Weisse Dame, im Auftrag des Vorstands m\u00f6chte ich \u00fcber die aktuell wichtigsten Entwicklungen in unserem Verein im Bereich des Schachspiels f\u00fcr Erwachsene informieren. &nbsp; Interner Spielbetrieb: &hellip; Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-21T06:30:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-21T06:48:22+00:00\" \/>\n<meta name=\"author\" content=\"Kai-Gerrit Venske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kai-Gerrit Venske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Kai-Gerrit Venske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/\"},\"author\":{\"name\":\"Kai-Gerrit Venske\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/d0bb0bc1ba7dbf44e2387b92ba199b43\"},\"headline\":\"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation\",\"datePublished\":\"2022-03-21T06:30:52+00:00\",\"dateModified\":\"2022-03-21T06:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/\"},\"wordCount\":1384,\"commentCount\":0,\"articleSection\":[\"Organisatorisches\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/\",\"name\":\"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2022-03-21T06:30:52+00:00\",\"dateModified\":\"2022-03-21T06:48:22+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/d0bb0bc1ba7dbf44e2387b92ba199b43\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2022\\\/03\\\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/d0bb0bc1ba7dbf44e2387b92ba199b43\",\"name\":\"Kai-Gerrit Venske\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/kai_gerrit_venske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/","og_locale":"de_DE","og_type":"article","og_title":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.","og_description":"Liebe Mitglieder des SC Weisse Dame, im Auftrag des Vorstands m\u00f6chte ich \u00fcber die aktuell wichtigsten Entwicklungen in unserem Verein im Bereich des Schachspiels f\u00fcr Erwachsene informieren. &nbsp; Interner Spielbetrieb: &hellip; Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2022-03-21T06:30:52+00:00","article_modified_time":"2022-03-21T06:48:22+00:00","author":"Kai-Gerrit Venske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Kai-Gerrit Venske","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten","Written by":"Kai-Gerrit Venske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/"},"author":{"name":"Kai-Gerrit Venske","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/d0bb0bc1ba7dbf44e2387b92ba199b43"},"headline":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation","datePublished":"2022-03-21T06:30:52+00:00","dateModified":"2022-03-21T06:48:22+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/"},"wordCount":1384,"commentCount":0,"articleSection":["Organisatorisches"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/","name":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2022-03-21T06:30:52+00:00","dateModified":"2022-03-21T06:48:22+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/d0bb0bc1ba7dbf44e2387b92ba199b43"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2022\/03\/fruehjahrsbotschaft-des-1-vorsitzenden-des-sc-weisse-dame-zur-aktuellen-vereinssituation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Fr\u00fchjahrsmitteilung des 1. Vorsitzenden des SC Weisse Dame zur aktuellen Vereinssituation"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/d0bb0bc1ba7dbf44e2387b92ba199b43","name":"Kai-Gerrit Venske","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/kai_gerrit_venske\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/22806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=22806"}],"version-history":[{"count":9,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/22806\/revisions"}],"predecessor-version":[{"id":22818,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/22806\/revisions\/22818"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=22806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=22806"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=22806"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=22806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}