{"id":21517,"date":"2021-10-21T23:59:43","date_gmt":"2021-10-21T21:59:43","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=21517"},"modified":"2021-10-23T21:43:12","modified_gmt":"2021-10-23T19:43:12","slug":"freitag-15-10-21-schnellschach-2","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/","title":{"rendered":"Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<div style=\"text-align: justify;\">\n<div>\u00a0<\/div>\n<div style=\"text-align: justify;\">Liebe Mitglieder, liebe Freundinnen und Freunde\u00a0 der Weissen Dame,<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">am <strong>Freitag, 22.10.2021<\/strong> findet ein <span style=\"color: #0000ff;\"><strong><span style=\"color: #000000;\">Vortrag von<\/span> Cord Wischh\u00f6fer <\/strong><\/span>statt. Hierin wird speziell beleuchtet, wie der langj\u00e4hrige <strong>Schachweltmeister Emanuel Lasker<\/strong> als <span style=\"color: #333399;\"><em>&#8222;der Gr\u00f6\u00dfte von allen die Weltmeister besiegte.&#8220;<\/em><\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Der Referent, selbst ein starker Schachspieler, ist als Weltreisender in Sachen Schachweltmeister bekannt. Er hat bereits einige Gr\u00e4ber ehemaliger Schachweltmeister besucht &#8211; zuletzt <span style=\"color: #333399;\"><a style=\"color: #333399;\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2019\/12\/wilhelm-der-erste-ein-besuch-bei-weltmeister-steinitz-in-brooklyn\/\"><em>Wilhelm Steinitz in New York<\/em><\/a> <\/span>&#8211; und entsprechende <span style=\"color: #000000;\">Reisebeitr\u00e4ge auf der WeDa-Homepage <\/span>ver\u00f6ffentlicht.<strong><br \/>\n<\/strong><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Freuen wir uns also auf gehaltvolle Partien und einen hochinteressanten, erbaulichen Vortrag!<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Viel Spa\u00df am kommenden Freitag w\u00fcnschen,<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Heinz, Robert und Torsten<\/div>\n<\/div>\n<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">PS.<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div>\n<div style=\"text-align: justify;\">Im Gro\u00dfen Saal d\u00fcrfen sich 20 Personen aufhalten. Da bei den letzten Terminen diese H\u00f6chstzahl nicht erreicht wurde, bedarf es keiner Anmeldung.<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Bitte beachtet das Hygienekonzept des Vereins, das auf unserer Seite in der aktuellen Fassung hinterlegt ist, und die im Haus geltenden 3G-Regeln; also bitte ggf. entsprechende Dokumente mitbringen.<\/div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Liebe Mitglieder, liebe Freundinnen und Freunde\u00a0 der Weissen Dame, \u00a0 am Freitag, 22.10.2021 findet ein Vortrag von Cord Wischh\u00f6fer statt. Hierin wird speziell beleuchtet, wie der langj\u00e4hrige Schachweltmeister Emanuel &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[36],"tags":[],"coauthors":[61,50],"class_list":["post-21517","post","type-post","status-publish","format-standard","hentry","category-historisches"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freitag, 22.10.21 ab 19:30 Uhr: &quot;Emanuel Lasker&quot; - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freitag, 22.10.21 ab 19:30 Uhr: &quot;Emanuel Lasker&quot; - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Liebe Mitglieder, liebe Freundinnen und Freunde\u00a0 der Weissen Dame, \u00a0 am Freitag, 22.10.2021 findet ein Vortrag von Cord Wischh\u00f6fer statt. Hierin wird speziell beleuchtet, wie der langj\u00e4hrige Schachweltmeister Emanuel &hellip; Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T21:59:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-23T19:43:12+00:00\" \/>\n<meta name=\"author\" content=\"Torsten Meyer, Christian Greiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Torsten Meyer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Torsten Meyer, Christian Greiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/\"},\"author\":{\"name\":\"Torsten Meyer\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/f261282b3f6a9ae553b330e3adb22229\"},\"headline\":\"Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer\",\"datePublished\":\"2021-10-21T21:59:43+00:00\",\"dateModified\":\"2021-10-23T19:43:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/\"},\"wordCount\":165,\"commentCount\":0,\"articleSection\":[\"Historisches\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/\",\"name\":\"Freitag, 22.10.21 ab 19:30 Uhr: \\\"Emanuel Lasker\\\" - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2021-10-21T21:59:43+00:00\",\"dateModified\":\"2021-10-23T19:43:12+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/f261282b3f6a9ae553b330e3adb22229\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/10\\\/freitag-15-10-21-schnellschach-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e. V.\",\"description\":\"Herzlich Willkommen!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/f261282b3f6a9ae553b330e3adb22229\",\"name\":\"Torsten Meyer\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/torsten_meyer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freitag, 22.10.21 ab 19:30 Uhr: \"Emanuel Lasker\" - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/","og_locale":"de_DE","og_type":"article","og_title":"Freitag, 22.10.21 ab 19:30 Uhr: \"Emanuel Lasker\" - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.","og_description":"\u00a0 Liebe Mitglieder, liebe Freundinnen und Freunde\u00a0 der Weissen Dame, \u00a0 am Freitag, 22.10.2021 findet ein Vortrag von Cord Wischh\u00f6fer statt. Hierin wird speziell beleuchtet, wie der langj\u00e4hrige Schachweltmeister Emanuel &hellip; Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/","og_site_name":"SC Weisse Dame e. V.","article_published_time":"2021-10-21T21:59:43+00:00","article_modified_time":"2021-10-23T19:43:12+00:00","author":"Torsten Meyer, Christian Greiser","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Torsten Meyer","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Torsten Meyer, Christian Greiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/"},"author":{"name":"Torsten Meyer","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/f261282b3f6a9ae553b330e3adb22229"},"headline":"Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer","datePublished":"2021-10-21T21:59:43+00:00","dateModified":"2021-10-23T19:43:12+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/"},"wordCount":165,"commentCount":0,"articleSection":["Historisches"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/","name":"Freitag, 22.10.21 ab 19:30 Uhr: \"Emanuel Lasker\" - Vortrag von Cord Wischh\u00f6fer - SC Weisse Dame e. V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2021-10-21T21:59:43+00:00","dateModified":"2021-10-23T19:43:12+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/f261282b3f6a9ae553b330e3adb22229"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/10\/freitag-15-10-21-schnellschach-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Freitag, 22.10.21 ab 19:30 Uhr: &#8222;Emanuel Lasker&#8220; &#8211; Vortrag von Cord Wischh\u00f6fer"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e. V.","description":"Herzlich Willkommen!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/f261282b3f6a9ae553b330e3adb22229","name":"Torsten Meyer","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/torsten_meyer\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/21517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=21517"}],"version-history":[{"count":8,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/21517\/revisions"}],"predecessor-version":[{"id":21535,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/21517\/revisions\/21535"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=21517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=21517"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=21517"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=21517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}