{"id":19962,"date":"2021-06-17T23:59:51","date_gmt":"2021-06-17T21:59:51","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=19962"},"modified":"2021-06-21T10:13:56","modified_gmt":"2021-06-21T08:13:56","slug":"q-liga-r123","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/","title":{"rendered":"Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;"},"content":{"rendered":"<p><span style=\"text-decoration: underline; color: #0000ff;\"><strong>Q-Liga-Bericht (R123):<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Die gl\u00e4nzend aufgelegten <span style=\"color: #0000ff;\"><strong>jka<\/strong> <\/span>und <span style=\"color: #0000ff;\"><strong>Belisar603<\/strong> <\/span>waren leider nicht genug, um noch auf Platz 3 zu springen. Es fehlte bei acht Punkten R\u00fcckstand nicht einmal viel, aber ganz reichte es eben doch nicht. Immerhin blieb uns das <strong>Kreuzberger Abstiegsschicksal<\/strong> erspart, so dass wir mit der neuen <span style=\"color: #0000ff;\"><em>WeDa-Liebe &#8222;3+0&#8220;<\/em><\/span> am kommenden Sonntag einen weiteren Aufstiegsversuch starten k\u00f6nnen &#8230;<\/p>\n<hr \/>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #808080;\"><strong>Q-Liga (R123): Donnerstag, 17.06.2021, 20:01 &#8211; 21:41 Uhr (5 min + 0 sec) &#8211; <a style=\"color: #808080;\" href=\"https:\/\/lichess.org\/tournament\/iHSCOLMo\"><span style=\"text-decoration: underline;\">Hier geht&#8217;s zum Turnier<\/span><\/a><\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19973\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg\" alt=\"\" width=\"1000\" height=\"526\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg 1729w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle-600x315.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle-1536x808.jpg 1536w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<hr \/>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>NEWS vom 17.06.2021 \/ CG<\/p>\n<p><span style=\"text-decoration: underline; color: #0000ff;\"><strong>Q-Liga-Vorbericht (R123):<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Anl\u00e4sslich unseres heutigen Aufeinandertreffens mit den <strong>Kreuzbergern (6C)<\/strong> folgt ein kurzer \u00dcberblick \u00fcber die Berliner Q-Ligaszene.<\/p>\n<p style=\"text-align: justify;\">Die <strong>SF Berlin 1903 (2.BL)<\/strong> sind das Ma\u00df aller Dinge in Berlin, gefolgt von den <strong>Tegeler K\u00f6nigen (3A)<\/strong>. Wieder nach oben gearbeitet haben sich\u00a0 die <strong>Freunde von DrBergerBerger (4A)<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ein wenig unterm Radar haben sich die <strong>Mariendorfer vom TSV 1897<\/strong> <strong>(6B)<\/strong> seit dem 7. M\u00e4rz 2021 hochgespielt. Dabei geschah dies keineswegs heimlich, still und leise, denn auf der TSV-Homepage gibt es jeweils zeitnahe Kurzberichte (<em><span style=\"text-decoration: underline;\"><span style=\"color: #333399; text-decoration: underline;\"><a style=\"color: #333399; text-decoration: underline;\" href=\"https:\/\/www.mariendorf-schach.de\/quarant%C3%A4neliga\/\">hier<\/a><\/span><\/span><\/em>) zu jeder der bisherigen 28 mitgespielten Runden.<\/p>\n<p style=\"text-align: justify;\">Den <strong>SNOBs (7C)<\/strong> folgt mit ein wenig Abstand das Team <strong>BSV (9C)<\/strong>. In den zweistelligen Bereich sind u. a. <strong>Zitadelle Spandau<\/strong> und <strong>Mattnetz<\/strong> abgerutscht. Bei beiden Vereinen treten bei weitem nicht mehr genug SpielerInnen an, um nach h\u00f6heren Zielen zu streben. Schade &#8230;<\/p>\n<p style=\"text-align: justify;\">Vielleicht sollten diese Vereine analog zu den <strong>Queer-Springern<\/strong> (<span style=\"text-decoration: underline;\"><em><span style=\"color: #333399;\"><a style=\"color: #333399; text-decoration: underline;\" href=\"http:\/\/www.queer-springer.de\/?id=news_item&amp;news_id=1623316442\">&#8222;Wir sind dann mal bis zum 25. Juli 2021 weg!&#8220;<\/a><\/span><\/em><\/span>) einfach mal eine Auszeit nehmen, um sich zu regenerieren. Offensichtlich ist dies in Absprache mit den Turnierorganisatoren m\u00f6glich.<\/p>\n<p style=\"text-align: justify;\"><strong>Eckbauer (11C), Rochade Berlin (14C)<\/strong> und <strong>NARVA (16B)<\/strong> sind weiterhin aktiv.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Q-Liga-Bericht (R123): Die gl\u00e4nzend aufgelegten jka und Belisar603 waren leider nicht genug, um noch auf Platz 3 zu springen. Es fehlte bei acht Punkten R\u00fcckstand nicht einmal viel, aber ganz &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/\" class=\"more-link\"><span class=\"screen-reader-text\">Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[156],"tags":[],"coauthors":[50,49],"class_list":["post-19962","post","type-post","status-publish","format-standard","hentry","category-q-liga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Q-Liga (R123): &quot;Dicht daneben ist auch vorbei!&quot; - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q-Liga (R123): &quot;Dicht daneben ist auch vorbei!&quot; - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Q-Liga-Bericht (R123): Die gl\u00e4nzend aufgelegten jka und Belisar603 waren leider nicht genug, um noch auf Platz 3 zu springen. Es fehlte bei acht Punkten R\u00fcckstand nicht einmal viel, aber ganz &hellip; Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220; weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T21:59:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-21T08:13:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg\" \/>\n<meta name=\"author\" content=\"Christian Greiser, Thorsten Gro\u00df\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Greiser\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christian Greiser, Thorsten Gro\u00df\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/\"},\"author\":{\"name\":\"Christian Greiser\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\"},\"headline\":\"Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;\",\"datePublished\":\"2021-06-17T21:59:51+00:00\",\"dateModified\":\"2021-06-21T08:13:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/\"},\"wordCount\":261,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Q-Liga-R123-Schlusstabelle.jpg\",\"articleSection\":[\"Q-Liga\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/\",\"name\":\"Q-Liga (R123): \\\"Dicht daneben ist auch vorbei!\\\" - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Q-Liga-R123-Schlusstabelle.jpg\",\"datePublished\":\"2021-06-17T21:59:51+00:00\",\"dateModified\":\"2021-06-21T08:13:56+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#primaryimage\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Q-Liga-R123-Schlusstabelle.jpg\",\"contentUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Q-Liga-R123-Schlusstabelle.jpg\",\"width\":1729,\"height\":909},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2021\\\/06\\\/q-liga-r123\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/c262da3a19176713e7a6632f64caa946\",\"name\":\"Christian Greiser\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/christian_greiser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q-Liga (R123): \"Dicht daneben ist auch vorbei!\" - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/","og_locale":"de_DE","og_type":"article","og_title":"Q-Liga (R123): \"Dicht daneben ist auch vorbei!\" - SC Weisse Dame e.V.","og_description":"Q-Liga-Bericht (R123): Die gl\u00e4nzend aufgelegten jka und Belisar603 waren leider nicht genug, um noch auf Platz 3 zu springen. Es fehlte bei acht Punkten R\u00fcckstand nicht einmal viel, aber ganz &hellip; Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220; weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2021-06-17T21:59:51+00:00","article_modified_time":"2021-06-21T08:13:56+00:00","og_image":[{"url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg","type":"","width":"","height":""}],"author":"Christian Greiser, Thorsten Gro\u00df","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Greiser","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten","Written by":"Christian Greiser, Thorsten Gro\u00df"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/"},"author":{"name":"Christian Greiser","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946"},"headline":"Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;","datePublished":"2021-06-17T21:59:51+00:00","dateModified":"2021-06-21T08:13:56+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/"},"wordCount":261,"commentCount":0,"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg","articleSection":["Q-Liga"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/","name":"Q-Liga (R123): \"Dicht daneben ist auch vorbei!\" - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"primaryImageOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#primaryimage"},"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg","datePublished":"2021-06-17T21:59:51+00:00","dateModified":"2021-06-21T08:13:56+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#primaryimage","url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg","contentUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2021\/06\/Q-Liga-R123-Schlusstabelle.jpg","width":1729,"height":909},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2021\/06\/q-liga-r123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Q-Liga (R123): &#8222;Dicht daneben ist auch vorbei!&#8220;"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/c262da3a19176713e7a6632f64caa946","name":"Christian Greiser","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/christian_greiser\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/19962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=19962"}],"version-history":[{"count":10,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/19962\/revisions"}],"predecessor-version":[{"id":20010,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/19962\/revisions\/20010"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=19962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=19962"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=19962"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=19962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}