{"id":18054,"date":"2020-11-22T16:45:55","date_gmt":"2020-11-22T15:45:55","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=18054"},"modified":"2021-12-22T01:25:59","modified_gmt":"2021-12-22T00:25:59","slug":"q-liga-r66-2","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/","title":{"rendered":"Q-Liga (R65): Berliner Dreifachtriumph !!!"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong style=\"color: #0000ff; text-decoration: underline;\">Q-Liga (R65) Bericht<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Der Donnerstagabend endete etwas unerwartet mit einem totalen Triumph der drei teilnehmenden Berliner Vereine. <strong><span style=\"color: #ff9900;\">IM <\/span>DrBergerBergers Freunde <\/strong>holten, angef\u00fchrt vom mysteri\u00f6sen Topscorer <strong>arne1988<\/strong>, den sicheren Staffelsieg. <strong>Zitadelle Spandau<\/strong> landete auf Platz 2 erneut vor den <span style=\"color: #0000ff;\"><strong>Weissen Damen <\/strong><\/span>auf dem letzten Aufstiegsplatz 3, obwohl unser \u00fcblicher Top-Scorer B. diesmal einen schwarzen Abend erwischte. Zitat: <em>&#8222;<span style=\"color: #3366ff;\">Ich will nie wieder ein Schachbrett sehen!<\/span>&#8222;<\/em><\/p>\n<p style=\"text-align: justify;\">Daf\u00fcr sprangen andere Spieler erfolgreich in die Bresche. Unserer Nachwuchsspielerin <strong>Sissi111<\/strong> gelang zwar nicht der Sprung in die Wertung der besten sieben Teilnehmer, aber folgende Stellungsperle sorgte bei der nachtr\u00e4glichen Analyse f\u00fcr Heiterkeit &#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_18055\" aria-describedby=\"caption-attachment-18055\" style=\"width: 404px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/lichess.org\/wUMbpPiM\/white\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18055 size-full\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg\" alt=\"\" width=\"404\" height=\"404\" \/><\/a><figcaption id=\"caption-attachment-18055\" class=\"wp-caption-text\">Sissi111 &#8211; CM Akhairat (Schwarz am Zug)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Wei\u00df hat den in der Er\u00f6ffnung erlittenen materiellen Nachteil in einen gewaltigen Entwicklungsvorsprung umgewandelt. Schwarz rettete mit 20&#8230;Tf8-e8 zwar seinen Turm, aber nach 21.Lh6-g7 wurde die Dame in der Ecke gefangen. Ein Bild f\u00fcr die G\u00f6tter! <strong><a href=\"https:\/\/lichess.org\/wUMbpPiM\/white#1\">Die ganze Partie zum Nachspielen hier.<\/a><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><span style=\"color: #808080;\"><strong>Q-Liga (R65): Donnerstag, 19.11., 20:01 \u2013 21:41 Uhr (3 min + 2 sec) \u2013 <\/strong><a style=\"color: #808080;\" href=\"https:\/\/lichess.org\/tournament\/T7NrqSHl\"><span style=\"text-decoration: underline;\"><strong>Hier geht\u2019s zum Turnier!<\/strong><\/span><\/a><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18066\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Q-Liga-R65-Schlusstabelle.jpg\" alt=\"\" width=\"1752\" height=\"937\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Q-Liga-R65-Schlusstabelle.jpg 1752w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Q-Liga-R65-Schlusstabelle-600x321.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Q-Liga-R65-Schlusstabelle-1536x821.jpg 1536w\" sizes=\"auto, (max-width: 1752px) 100vw, 1752px\" \/><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>NEWS vom 22.11.2020 \/ TG<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\"><strong>Q-Liga (R65) Vorbericht<\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\">Heute Abend geht es f\u00fcr die <strong>Weisse Dame<\/strong> gleich gegen mehrere gute alte Bekannte, darunter f\u00e4llt die Begegnung gegen die Westpokalrivalen von <strong>Zitadelle Spandau<\/strong> (siehe auch: <em>&#8222;<a href=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/freitag-der-13-pech-gehabt\/\">Freitag, der 13., Pech gehabt !?<\/a>&#8222;<\/em> ), die <strong>Freunde von IM DrBergerBerger<\/strong> (formerly known as: <strong>Lichtenrader Cityleagueshaver<\/strong>) und last but not least die <strong>Boddenkieker <\/strong><strong>von Greifswalde<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Q-Liga (R65) Bericht Der Donnerstagabend endete etwas unerwartet mit einem totalen Triumph der drei teilnehmenden Berliner Vereine. IM DrBergerBergers Freunde holten, angef\u00fchrt vom mysteri\u00f6sen Topscorer arne1988, den sicheren Staffelsieg. Zitadelle &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">Q-Liga (R65): Berliner Dreifachtriumph !!!<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[156],"tags":[],"coauthors":[49,50],"class_list":["post-18054","post","type-post","status-publish","format-standard","hentry","category-q-liga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Q-Liga (R65) Bericht Der Donnerstagabend endete etwas unerwartet mit einem totalen Triumph der drei teilnehmenden Berliner Vereine. IM DrBergerBergers Freunde holten, angef\u00fchrt vom mysteri\u00f6sen Topscorer arne1988, den sicheren Staffelsieg. Zitadelle &hellip; Q-Liga (R65): Berliner Dreifachtriumph !!! weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-22T15:45:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-22T00:25:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg\" \/>\n<meta name=\"author\" content=\"Thorsten Gro\u00df, Christian Greiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thorsten Gro\u00df\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Thorsten Gro\u00df, Christian Greiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/\"},\"author\":{\"name\":\"Thorsten Gro\u00df\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/ce9002278de6d6d5f4fa69aa251fa211\"},\"headline\":\"Q-Liga (R65): Berliner Dreifachtriumph !!!\",\"datePublished\":\"2020-11-22T15:45:55+00:00\",\"dateModified\":\"2021-12-22T00:25:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/\"},\"wordCount\":236,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sissi111-Akhairat.jpg\",\"articleSection\":[\"Q-Liga\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/\",\"name\":\"Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sissi111-Akhairat.jpg\",\"datePublished\":\"2020-11-22T15:45:55+00:00\",\"dateModified\":\"2021-12-22T00:25:59+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/ce9002278de6d6d5f4fa69aa251fa211\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sissi111-Akhairat.jpg\",\"contentUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sissi111-Akhairat.jpg\",\"width\":404,\"height\":404},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/11\\\/q-liga-r66-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Q-Liga (R65): Berliner Dreifachtriumph !!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/ce9002278de6d6d5f4fa69aa251fa211\",\"name\":\"Thorsten Gro\u00df\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/thorsten_gross\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/","og_locale":"de_DE","og_type":"article","og_title":"Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.","og_description":"Q-Liga (R65) Bericht Der Donnerstagabend endete etwas unerwartet mit einem totalen Triumph der drei teilnehmenden Berliner Vereine. IM DrBergerBergers Freunde holten, angef\u00fchrt vom mysteri\u00f6sen Topscorer arne1988, den sicheren Staffelsieg. Zitadelle &hellip; Q-Liga (R65): Berliner Dreifachtriumph !!! weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2020-11-22T15:45:55+00:00","article_modified_time":"2021-12-22T00:25:59+00:00","og_image":[{"url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg","type":"","width":"","height":""}],"author":"Thorsten Gro\u00df, Christian Greiser","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thorsten Gro\u00df","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Thorsten Gro\u00df, Christian Greiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/"},"author":{"name":"Thorsten Gro\u00df","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/ce9002278de6d6d5f4fa69aa251fa211"},"headline":"Q-Liga (R65): Berliner Dreifachtriumph !!!","datePublished":"2020-11-22T15:45:55+00:00","dateModified":"2021-12-22T00:25:59+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/"},"wordCount":236,"commentCount":0,"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg","articleSection":["Q-Liga"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/","name":"Q-Liga (R65): Berliner Dreifachtriumph !!! - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"primaryImageOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#primaryimage"},"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg","datePublished":"2020-11-22T15:45:55+00:00","dateModified":"2021-12-22T00:25:59+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/ce9002278de6d6d5f4fa69aa251fa211"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#primaryimage","url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg","contentUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/11\/Sissi111-Akhairat.jpg","width":404,"height":404},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/11\/q-liga-r66-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Q-Liga (R65): Berliner Dreifachtriumph !!!"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/ce9002278de6d6d5f4fa69aa251fa211","name":"Thorsten Gro\u00df","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/thorsten_gross\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/18054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=18054"}],"version-history":[{"count":11,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/18054\/revisions"}],"predecessor-version":[{"id":22226,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/18054\/revisions\/22226"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=18054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=18054"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=18054"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=18054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}