{"id":15547,"date":"2020-04-27T12:04:39","date_gmt":"2020-04-27T10:04:39","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?p=15547"},"modified":"2021-02-06T12:06:19","modified_gmt":"2021-02-06T11:06:19","slug":"2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2","status":"publish","type":"post","link":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/","title":{"rendered":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\"><strong>Q-Liga-Bericht (R7):<\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\">Wir treten zweifelsohne auf der Stelle! Aber nach zweimaligem Auf- und Abstieg g\u00f6nnen wir uns einfach mal einen Moment des Atemholens. Der Klassenerhalt in 4C war in beide Richtungen klar, sodass an dieser Stelle auch einmal einige besondere Details hervorgehoben werden d\u00fcrfen. So kamen erstmalig acht Spieler in die Wertung, was sich bei unserer mannschaftlichen Geschlossenheit \u00e4u\u00dferst positiv auswirkt.<\/p>\n<p style=\"text-align: justify;\">\u00dcbrigens kann sich keiner der Arrivierten mehr sicher sein, automatisch in diese Wertung einzuflie\u00dfen, denn: <span style=\"color: #0000ff;\"><strong>SISSI111<\/strong> <\/span>r\u00fcckt dem Establishment auf den Pelz! Mit starken 19 Punkten aus 35 Partien (Top-3-Wert) mischte sie eine ganze Reihe deutlich besser eingesch\u00e4tzter SpielerInnen auf. Die besondere Spezialit\u00e4t der Neunj\u00e4hrigen sind dabei geschickt eingestreute Remisangebote, von denen ihre GegnerInnen mal mehr und mal weniger angetan sind.<\/p>\n<figure id=\"attachment_15549\" aria-describedby=\"caption-attachment-15549\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/lichess.org\/wP3n5pIH\/black\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15549\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg\" alt=\"\" width=\"1000\" height=\"443\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg 1606w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111-600x266.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111-1536x681.jpg 1536w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15549\" class=\"wp-caption-text\">Eine besonders bittere Pille musste dabei <strong>MacDuhn<\/strong> schlucken, der in ausgeglichener Stellung bei etwas besserer Zeit den fatalen Entschluss fasste ungebremst auf Sieg zu spielen und dabei eine winzige Kleinigkeit au\u00dfer acht lie\u00df. Vielleicht h\u00e4tte er sich mit dem objektiv korrekten Remisangebot anfreunden sollen! Aber, jeder lernt halt anders &#8230; <a href=\"https:\/\/lichess.org\/wP3n5pIH\/black\"><span style=\"color: #3366ff;\">(Zum Nachspielen bitte auf die Grafik klicken)<\/span><\/a><\/figcaption><\/figure>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15550\" aria-describedby=\"caption-attachment-15550\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/lichess.org\/yK0vK4Oq\/white\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15550\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7.21-4C-SISSI111.jpg\" alt=\"\" width=\"1000\" height=\"444\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7.21-4C-SISSI111.jpg 1600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7.21-4C-SISSI111-600x267.jpg 600w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7.21-4C-SISSI111-1536x683.jpg 1536w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15550\" class=\"wp-caption-text\">Ganz oben d\u00fcrfte SISSI111 auf der Freundesliste von <strong>LicantropoSiciliano<\/strong> stehen, bot sie ihm doch gro\u00dfherzig eine Punkteteilung bei seinen nur noch gut zwei Sekunden Restbedenkzeit an. Er d\u00fcrfte einigerma\u00dfen erleichtert angenommen haben.\u00a0\u00a0 \u00a0<span style=\"color: #141412; font-size: 15px;\">\ud83d\ude09\u00a0 \u00a0<\/span> <a href=\"https:\/\/lichess.org\/yK0vK4Oq\/white\"><span style=\"color: #3366ff;\">(Zum Nachspielen bitte auf die Grafik klicken)<\/span><\/a><\/figcaption><\/figure>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #808080;\"><strong>Q-Liga (R7): Sonntagtag, 26.04.,<\/strong> <strong>20:<span style=\"color: #808080;\">08-22:08 Uhr (3 min + 0 sec)<\/span><\/strong> &#8211; <a style=\"color: #808080;\" href=\"https:\/\/lichess.org\/tournament\/6Goh8F2r\"><span style=\"text-decoration: underline;\"><strong>Hier geht&#8217;s zum Turnier!<\/strong><\/span><\/a><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15548 aligncenter\" src=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C.jpg\" alt=\"\" width=\"1384\" height=\"947\" srcset=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C.jpg 1384w, http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-600x411.jpg 600w\" sizes=\"auto, (max-width: 1384px) 100vw, 1384px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Q-Liga-Bericht (R7): Wir treten zweifelsohne auf der Stelle! Aber nach zweimaligem Auf- und Abstieg g\u00f6nnen wir uns einfach mal einen Moment des Atemholens. Der Klassenerhalt in 4C war in beide &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[156],"tags":[],"coauthors":[47,49,50],"class_list":["post-15547","post","type-post","status-publish","format-standard","hentry","category-q-liga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Q-Liga-Bericht (R7): Wir treten zweifelsohne auf der Stelle! Aber nach zweimaligem Auf- und Abstieg g\u00f6nnen wir uns einfach mal einen Moment des Atemholens. Der Klassenerhalt in 4C war in beide &hellip; Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T10:04:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-06T11:06:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg\" \/>\n<meta name=\"author\" content=\"Claudia M\u00fcnstermann, Thorsten Gro\u00df, Christian Greiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudia M\u00fcnstermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Claudia M\u00fcnstermann, Thorsten Gro\u00df, Christian Greiser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/\"},\"author\":{\"name\":\"Claudia M\u00fcnstermann\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/1703a3cc46301ab8345eabbe22b28f8a\"},\"headline\":\"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen\",\"datePublished\":\"2020-04-27T10:04:39+00:00\",\"dateModified\":\"2021-02-06T11:06:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/\"},\"wordCount\":267,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Q-Liga-R7-4C-SISSI111.jpg\",\"articleSection\":[\"Q-Liga\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/\",\"name\":\"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Q-Liga-R7-4C-SISSI111.jpg\",\"datePublished\":\"2020-04-27T10:04:39+00:00\",\"dateModified\":\"2021-02-06T11:06:19+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/1703a3cc46301ab8345eabbe22b28f8a\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Q-Liga-R7-4C-SISSI111.jpg\",\"contentUrl\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Q-Liga-R7-4C-SISSI111.jpg\",\"width\":1606,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/2020\\\/04\\\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#\\\/schema\\\/person\\\/1703a3cc46301ab8345eabbe22b28f8a\",\"name\":\"Claudia M\u00fcnstermann\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/author\\\/claudia_muenstermann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/","og_locale":"de_DE","og_type":"article","og_title":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.","og_description":"Q-Liga-Bericht (R7): Wir treten zweifelsohne auf der Stelle! Aber nach zweimaligem Auf- und Abstieg g\u00f6nnen wir uns einfach mal einen Moment des Atemholens. Der Klassenerhalt in 4C war in beide &hellip; Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/","og_site_name":"SC Weisse Dame e.V.","article_published_time":"2020-04-27T10:04:39+00:00","article_modified_time":"2021-02-06T11:06:19+00:00","og_image":[{"url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg","type":"","width":"","height":""}],"author":"Claudia M\u00fcnstermann, Thorsten Gro\u00df, Christian Greiser","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Claudia M\u00fcnstermann","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten","Written by":"Claudia M\u00fcnstermann, Thorsten Gro\u00df, Christian Greiser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#article","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/"},"author":{"name":"Claudia M\u00fcnstermann","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/1703a3cc46301ab8345eabbe22b28f8a"},"headline":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen","datePublished":"2020-04-27T10:04:39+00:00","dateModified":"2021-02-06T11:06:19+00:00","mainEntityOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/"},"wordCount":267,"commentCount":0,"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg","articleSection":["Q-Liga"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/","url":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/","name":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"primaryImageOfPage":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#primaryimage"},"image":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#primaryimage"},"thumbnailUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg","datePublished":"2020-04-27T10:04:39+00:00","dateModified":"2021-02-06T11:06:19+00:00","author":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/1703a3cc46301ab8345eabbe22b28f8a"},"breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#primaryimage","url":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg","contentUrl":"http:\/\/sc-weisse-dame.de\/v3\/wp-content\/uploads\/2020\/04\/Q-Liga-R7-4C-SISSI111.jpg","width":1606,"height":712},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/2020\/04\/2-weda-internet-blitzschachturnier-startet-heute-um-1900-uhr-2-2-3-2-3-3-3-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Q-Liga (R7): Klassenerhalt in 4C mit 14 WeDa-TeilnehmerInnen"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/sc-weisse-dame.de\/v3\/#\/schema\/person\/1703a3cc46301ab8345eabbe22b28f8a","name":"Claudia M\u00fcnstermann","url":"http:\/\/sc-weisse-dame.de\/v3\/author\/claudia_muenstermann\/"}]}},"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/15547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=15547"}],"version-history":[{"count":10,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/15547\/revisions"}],"predecessor-version":[{"id":18783,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/posts\/15547\/revisions\/18783"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=15547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/categories?post=15547"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/tags?post=15547"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=15547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}