{"id":34090,"date":"2026-01-04T21:27:54","date_gmt":"2026-01-04T20:27:54","guid":{"rendered":"http:\/\/sc-weisse-dame.de\/v3\/?page_id=34090"},"modified":"2026-07-10T21:46:55","modified_gmt":"2026-07-10T19:46:55","slug":"clubblitzschachmeisterschaft-2026","status":"publish","type":"page","link":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/","title":{"rendered":"Clubblitzschachmeisterschaft 2026"},"content":{"rendered":"<p>Zur Club-Blitzmeisterschaft 2026 werden wieder f\u00fcnf \u00fcber das Jahr verteilte Wertungsturniere ausgetragen. Diese werden als Rundenturniere im Zeitmodus 3 Minuten + 2 Sekunden pro Zug gespielt. Dabei erh\u00e4lt bei jedem Turnier der bestplatzierte Spieler 25 Punkte und jeder weitere Platz zwei weniger als der vorherige, aber mindestens einen. G\u00e4ste spielen dabei au\u00dfer Konkurrenz, werden bei der Punktevergabe also \u00fcbergangen. F\u00fcr Teilnehmer, die bei mehr als drei Turnieren mitspielen, werden nur die drei besten Turniere ber\u00fccksichtigt.<\/p>\n<p>Das <a href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/01\/clubblitzschachmeisterschaft-1-wertungsturnier\/\">erste Wertungsturnier<\/a> fand am 9.&nbsp;Januar statt.<\/p>\n<h4>Punktestand<\/h4>\n<div style=\"width: 100%; overflow-x:auto; white-space:nowrap;\">\n<table>\n<tr>\n<th>Rang<\/th>\n<th>Name<\/th>\n<th><a href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/01\/clubblitzschachmeisterschaft-1-wertungsturnier\/\">1. WT<\/a><\/th>\n<th><a href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/04\/clubblitzschachmeisterschaft-2-wertungsturnier-2\/\">2. WT<\/a><\/th>\n<th><a href=\"http:\/\/sc-weisse-dame.de\/v3\/2026\/07\/clubblitzschachmeisterschaft-drittes-wertungsturnier-2\/\">3. WT<\/a><\/th>\n<th>4. WT<\/th>\n<th>5. WT<\/th>\n<th>Gesamt<\/th>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td>Anton Bashtavy<\/td>\n<td>23<\/td>\n<td>25<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>48<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>Jakob Grimm<\/td>\n<td>21<\/td>\n<td><\/td>\n<td>25<\/td>\n<td><\/td>\n<td><\/td>\n<td>46<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>Bastian Deubler<\/td>\n<td>13<\/td>\n<td>17<\/td>\n<td>13<\/td>\n<td><\/td>\n<td><\/td>\n<td>43<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>Martin Sechting<\/td>\n<td><\/td>\n<td>23<\/td>\n<td>17<\/td>\n<td><\/td>\n<td><\/td>\n<td>40<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>Heinz Uhl<\/td>\n<td>3<\/td>\n<td>21<\/td>\n<td>15<\/td>\n<td><\/td>\n<td><\/td>\n<td>39<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td>Ingo Abraham<\/td>\n<td>15<\/td>\n<td><\/td>\n<td>23<\/td>\n<td><\/td>\n<td><\/td>\n<td>38<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td>Thorsten Gro\u00df<\/td>\n<td>17<\/td>\n<td>19<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>36<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td>Diyap B\u00fcy\u00fckasik<\/td>\n<td>25<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>25<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td>Ralf Mohrmann<\/td>\n<td>7<\/td>\n<td>15<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>22<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td>Richard Mertens<\/td>\n<td>11<\/td>\n<td><\/td>\n<td>11<\/td>\n<td><\/td>\n<td><\/td>\n<td>22<\/td>\n<\/tr>\n<tr>\n<td>11<\/td>\n<td>Oliver H\u00f6lscher<\/td>\n<td><\/td>\n<td><\/td>\n<td>21<\/td>\n<td><\/td>\n<td><\/td>\n<td>21<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>Carsten Miemietz<\/td>\n<td>1<\/td>\n<td><\/td>\n<td>19<\/td>\n<td><\/td>\n<td><\/td>\n<td>20<\/td>\n<\/tr>\n<tr>\n<td>13<\/td>\n<td>Yannick Kather<\/td>\n<td>19<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>19<\/td>\n<\/tr>\n<tr>\n<td>14<\/td>\n<td>Mario Tepe<\/td>\n<td>9<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>9<\/td>\n<\/tr>\n<tr>\n<td>14<\/td>\n<td>Thorsten Schulz<\/td>\n<td><\/td>\n<td><\/td>\n<td>9<\/td>\n<td><\/td>\n<td><\/td>\n<td>9<\/td>\n<\/tr>\n<tr>\n<td>16<\/td>\n<td>Jakub Sobotka<\/td>\n<td>5<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>5<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Gregor Bauer<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Dennis Bertuch<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Wesley Miemietz<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Bhavadeep Nettem<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Christian Greiser<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Cedric P\u00f6hlmann<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>Ben Schumacher<\/td>\n<td>1<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Club-Blitzmeisterschaft 2026 werden wieder f\u00fcnf \u00fcber das Jahr verteilte Wertungsturniere ausgetragen. Diese werden als Rundenturniere im Zeitmodus 3 Minuten + 2 Sekunden pro Zug gespielt. Dabei erh\u00e4lt bei jedem &hellip; <a href=\"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/\" class=\"more-link\"><span class=\"screen-reader-text\">Clubblitzschachmeisterschaft 2026<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":42,"featured_media":0,"parent":40,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"coauthors":[194],"class_list":["post-34090","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.\" \/>\n<meta property=\"og:description\" content=\"Zur Club-Blitzmeisterschaft 2026 werden wieder f\u00fcnf \u00fcber das Jahr verteilte Wertungsturniere ausgetragen. Diese werden als Rundenturniere im Zeitmodus 3 Minuten + 2 Sekunden pro Zug gespielt. Dabei erh\u00e4lt bei jedem &hellip; Clubblitzschachmeisterschaft 2026 weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"SC Weisse Dame e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T19:46:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Dennis Bertuch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/clubblitzschachmeisterschaft-2026\\\/\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/clubblitzschachmeisterschaft-2026\\\/\",\"name\":\"Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\"},\"datePublished\":\"2026-01-04T20:27:54+00:00\",\"dateModified\":\"2026-07-10T19:46:55+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/clubblitzschachmeisterschaft-2026\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/clubblitzschachmeisterschaft-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/clubblitzschachmeisterschaft-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spielbetrieb\",\"item\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/spielbetrieb\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clubblitzschachmeisterschaft 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/#website\",\"url\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/\",\"name\":\"SC Weisse Dame e.V.\",\"description\":\"75 Jahre jung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/sc-weisse-dame.de\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/","og_locale":"de_DE","og_type":"article","og_title":"Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.","og_description":"Zur Club-Blitzmeisterschaft 2026 werden wieder f\u00fcnf \u00fcber das Jahr verteilte Wertungsturniere ausgetragen. Diese werden als Rundenturniere im Zeitmodus 3 Minuten + 2 Sekunden pro Zug gespielt. Dabei erh\u00e4lt bei jedem &hellip; Clubblitzschachmeisterschaft 2026 weiterlesen &rarr;","og_url":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/","og_site_name":"SC Weisse Dame e.V.","article_modified_time":"2026-07-10T19:46:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten","Written by":"Dennis Bertuch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/","url":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/","name":"Clubblitzschachmeisterschaft 2026 - SC Weisse Dame e.V.","isPartOf":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/#website"},"datePublished":"2026-01-04T20:27:54+00:00","dateModified":"2026-07-10T19:46:55+00:00","breadcrumb":{"@id":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/clubblitzschachmeisterschaft-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/sc-weisse-dame.de\/v3\/"},{"@type":"ListItem","position":2,"name":"Spielbetrieb","item":"http:\/\/sc-weisse-dame.de\/v3\/spielbetrieb\/"},{"@type":"ListItem","position":3,"name":"Clubblitzschachmeisterschaft 2026"}]},{"@type":"WebSite","@id":"http:\/\/sc-weisse-dame.de\/v3\/#website","url":"http:\/\/sc-weisse-dame.de\/v3\/","name":"SC Weisse Dame e.V.","description":"75 Jahre jung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sc-weisse-dame.de\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/pages\/34090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/comments?post=34090"}],"version-history":[{"count":8,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/pages\/34090\/revisions"}],"predecessor-version":[{"id":35150,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/pages\/34090\/revisions\/35150"}],"up":[{"embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/pages\/40"}],"wp:attachment":[{"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/media?parent=34090"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"http:\/\/sc-weisse-dame.de\/v3\/wp-json\/wp\/v2\/coauthors?post=34090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}